{"id":39872,"date":"2019-11-25T09:57:10","date_gmt":"2019-11-25T17:57:10","guid":{"rendered":"https:\/\/mcecleanenergy.org\/two-more-cities-in-solano-contra-costa-counties-join-mce\/"},"modified":"2026-05-14T12:05:54","modified_gmt":"2026-05-14T19:05:54","slug":"two-more-cities-in-solano-contra-costa-counties-join-mce","status":"publish","type":"post","link":"https:\/\/mcecleanenergy.org\/de\/two-more-cities-in-solano-contra-costa-counties-join-mce\/","title":{"rendered":"Zwei weitere St\u00e4dte in den Bezirken Solano und Contra Costa treten MCE bei"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"39872\" class=\"elementor elementor-39872\" data-elementor-post-type=\"post\">\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-31593be e-flex e-con-boxed e-con e-parent\" data-id=\"31593be\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-1108671 e-flex e-con-boxed e-con e-child\" data-id=\"1108671\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-b44d3fe e-flex e-con-boxed e-con e-child\" data-id=\"b44d3fe\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-490cf9d e-flex e-con-boxed e-con e-child\" data-id=\"490cf9d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f778b21 elementor-widget elementor-widget-text-editor\" data-id=\"f778b21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Stromkunden in Pleasant Hill und Vallejo haben ab 2021 die Wahl und k\u00f6nnen sich f\u00fcr erneuerbare Energien entscheiden<\/h2>\n<p data-uw-styling-context=\"true\"><u><strong>ZUR SOFORTIGEN FREIGABE<\/strong><\/u>\n25. November 2019<\/p>\n<p data-uw-styling-context=\"true\"><u><strong>MCE Presse Kontakt:<\/strong><\/u><br role=\"presentation\" data-uw-styling-context=\"true\" data-uw-rm-sr=\"\" \/>Kalicia Pivirotto, Marketingleiterin\n(415) 464-6036 | <a href=\"mailto:kpivirotto@mcecleanenergy.org\" rel=\"noopener noreferrer\">kpivirotto@mcecleanenergy.org<\/a><\/p>\n<strong>SAN RAFAEL und CONCORD, Kalifornien. <\/strong>- Am 21. November 2019 hat der Vorstand von MCE die Mitgliedschaft der St\u00e4dte Vallejo und Pleasant Hill genehmigt und damit die Voraussetzungen daf\u00fcr geschaffen, dass MCE diesen Gemeinden eine Auswahl an Stromanbietern und sauberen Stromdienstleistungen anbieten kann. Vallejo und Pleasant Hill schlie\u00dfen sich den bestehenden 34 Mitgliedsgemeinden von MCE in den Countys Solano, Marin, Napa und Contra Costa an, die bereits an Kaliforniens erstem und dienst\u00e4ltestem Community Choice Aggregation (CCA)-Programm teilnehmen.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-071fc97 e-flex e-con-boxed e-con e-child\" data-id=\"071fc97\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c55c386 elementor-blockquote--align-left elementor-blockquote--skin-border elementor-widget elementor-widget-blockquote\" data-id=\"c55c386\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"blockquote.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<blockquote class=\"elementor-blockquote\">\n\t\t\t<p class=\"elementor-blockquote__content\">\n\t\t\t\t\"Die Partnerschaft mit MCE gibt den Einwohnern und Unternehmen in Vallejo eine Wahlm\u00f6glichkeit, die sie vorher nicht hatten\", sagte der stellvertretende B\u00fcrgermeister von Vallejo, Pippin Dew. \"Eine wettbewerbsf\u00e4hige Energieauswahl ist f\u00fcr unsere Gemeinde wichtig, und es ist aufregend, einen alternativen Energieversorger zu haben, der es den Einwohnern nicht nur erm\u00f6glicht, Teil der sauberen Energierevolution zu sein, sondern auch die Bem\u00fchungen der Gemeinde um die Schaffung von Arbeitspl\u00e4tzen vor Ort und die Entwicklung von Arbeitskr\u00e4ften und Wirtschaft unterst\u00fctzt.\"\t\t\t<\/p>\n\t\t\t\t\t<\/blockquote>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-0498b38 e-flex e-con-boxed e-con e-child\" data-id=\"0498b38\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b4ab24e elementor-widget elementor-widget-text-editor\" data-id=\"b4ab24e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tDie St\u00e4dte Vallejo und Pleasant Hill haben sich in den letzten zwei Jahren mit dem Thema \"Community Choice Energy\" befasst und MCE eingeladen, in mehreren \u00f6ffentlichen Foren zu sprechen. Beide St\u00e4dte haben Anfang des Jahres in \u00f6ffentlichen Stadtratsdiskussionen, bei denen die \u00d6ffentlichkeit zur Teilnahme aufgefordert wurde, einstimmig f\u00fcr eine Mitgliedschaft bei MCE gestimmt. Vorbehaltlich der Genehmigung des \u00fcberarbeiteten Umsetzungsplans von MCE durch die California Public Utilities Commission Anfang 2020 werden die Stromkunden von Vallejo und Pleasant Hill im Jahr 2021 von MCE beliefert werden.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-05dda51 elementor-blockquote--align-left elementor-blockquote--skin-border elementor-widget elementor-widget-blockquote\" data-id=\"05dda51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"blockquote.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<blockquote class=\"elementor-blockquote\">\n\t\t\t<p class=\"elementor-blockquote__content\">\n\t\t\t\t\"Pleasant Hill freut sich darauf, MCE beizutreten und unserer Gemeinde die M\u00f6glichkeit zu geben, selbst zu entscheiden, woher sie ihre Energie beziehen und wie sie erzeugt wird\", sagte der B\u00fcrgermeister von Pleasant Hill, Ken Carlson.\t\t\t<\/p>\n\t\t\t\t\t<\/blockquote>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b774e64 elementor-widget elementor-widget-text-editor\" data-id=\"b774e64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tDie 150.000 Gemeindemitglieder von Vallejo und Pleasant Hill repr\u00e4sentieren zusammen etwa 64.000 Stromkonten. Durch den Beitritt zu MCE haben die Einwohner und Unternehmen nicht nur die Wahl zwischen verschiedenen Energieversorgern, sondern k\u00f6nnen auch an lokalen Programmen f\u00fcr saubere Energie teilnehmen, Anreize f\u00fcr Elektrofahrzeuge und Ladestationen erhalten und von lokalen Besch\u00e4ftigungsm\u00f6glichkeiten profitieren. Die Versorgung der neuen Kunden w\u00fcrde die Menge an erneuerbarer Energie, die auf dem kalifornischen Energiemarkt genutzt wird, um etwa 110.666 MWh pro Jahr erh\u00f6hen und gleichzeitig die Treibhausgasemissionen um bis zu 122 Tonnen Kohlendioxid\u00e4quivalent pro Jahr reduzieren, so die Analyse*.\n\nDie Stadt Vallejo ist mit 122.000 Einwohnern die gr\u00f6\u00dfte Gemeinde im Solano County. MCE versorgt das Solano County seit 2015 mit der Stadt Benicia und wird im Fr\u00fchjahr 2020 auch das Solano County ohne eigenen Stadtbezirk versorgen. Pleasant Hill hat rund 35.000 Einwohner und ist die 15. Gemeinde im Contra Costa County, die sich MCE anschlie\u00dft. MCE ist seit 2013 im Contra Costa County t\u00e4tig, zun\u00e4chst in der Stadt Richmond. El Cerrito und San Pablo schlossen sich 2015 an, Lafayette und Walnut Creek im Jahr 2016 und die Gemeinden Concord, Danville, Martinez, Moraga, Oakley, Pinole, Pittsburg, San Ramon und das nicht eingemeindete Contra Costa County im Jahr 2018.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f57814 elementor-blockquote--align-left elementor-blockquote--skin-border elementor-widget elementor-widget-blockquote\" data-id=\"9f57814\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"blockquote.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<blockquote class=\"elementor-blockquote\">\n\t\t\t<p class=\"elementor-blockquote__content\">\n\t\t\t\t\"MCE f\u00fchlt sich geehrt, Pleasant Hill und Vallejo in unserem Versorgungsgebiet willkommen zu hei\u00dfen und dazu beizutragen, den Einwohnern und Unternehmen die Vorteile von Wahlm\u00f6glichkeiten und sauberer Energie zu bieten\", sagte Dawn Weisz, CEO von MCE. \"Unser gemeinsames Ziel ist es, Stromkunden zu bef\u00e4higen, in eine nachhaltigere Zukunft zu investieren.\"\t\t\t<\/p>\n\t\t\t\t\t<\/blockquote>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-66f02ff e-flex e-con-boxed e-con e-child\" data-id=\"66f02ff\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-90f3b5d elementor-widget elementor-widget-text-editor\" data-id=\"90f3b5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Andere Solano- und Contra-Costa-Gemeinden, die an einem Beitritt zu MCE interessiert sind, k\u00f6nnen sich an folgende Adresse wenden, um weitere Informationen zu erhalten <a href=\"mailto:engagement@mceCleanEnergy.org\">engagement@mceCleanEnergy.org<\/a>.<\/p><h6>*<a href=\"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2020\/01\/MCE-Board-Meeting-Packet-November_2019.pdf\" target=\"_blank\" rel=\"noopener noreferrer\" aria-label=\"mcecleanenergy.org\/wp-content\/uploads\/2020\/01\/MCE-Board-Meeting-Packet-November_2019.pdf - in einem neuen Tab \u00f6ffnen\" data-uw-rm-ext-link=\"\" data-uw-pdf-br=\"1\" data-uw-pdf-doc=\"\">mcecleanenergy.org\/wp-content\/uploads\/2020\/01\/MCE-Board-Meeting-Packet-November_2019.pdf<\/a>\u00a0(Seite 21)<\/h6>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e18d27 elementor-widget elementor-widget-text-editor\" data-id=\"7e18d27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">###<\/p><p><i>\u00dcber MCE: Als Kaliforniens erstes Community Choice Aggregation Program ist MCE eine bahnbrechende, gemeinn\u00fctzige, \u00f6ffentliche Einrichtung, die seit 2010 den Standard f\u00fcr Energieinnovationen in unseren Gemeinden setzt. MCE bietet sauberen Strom zu stabilen Tarifen, reduziert die energiebedingten Treibhausgasemissionen erheblich und erm\u00f6glicht Reinvestitionen in H\u00f6he von Millionen von Dollar in lokale Energieprogramme. MCE ist ein Lastversorgungsunternehmen mit einer Spitzenlast von 1.000 MW. MCE versorgt mehr als 480.000 Kunden und mehr als eine Million Einwohner und Unternehmen in 34 Mitgliedsgemeinden in vier Bezirken der Bay Area mit Strom: Napa, Marin, Contra Costa und Solano. Weitere Informationen \u00fcber MCE finden Sie unter <a href=\"https:\/\/mcecleanenergy.org\/de\/\" target=\"_blank\" rel=\"noopener noreferrer\">mceCleanEnergy.org<\/a><\/i><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64ab53f elementor-widget elementor-widget-text-editor\" data-id=\"64ab53f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2019\/11\/Two-More-Cities-in-Solano-and-Contra-Costa-Counties-Join-MCE.pdf\" target=\"_blank\" rel=\"noopener\">Pressemitteilung herunterladen<\/a> (pdf)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Electricity Customers in Pleasant Hill &amp; Vallejo to Gain Choice &amp; Renewable Energy Options in 2021 FOR IMMEDIATE RELEASE November 25, 2019 MCE Press Contact:Kalicia Pivirotto, Marketing Manager (415) 464-6036 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":39873,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_theme","format":"standard","meta":{"_acf_changed":false,"_searchwp_excluded":"","footnotes":""},"categories":[29],"tags":[392,693,614,912,708,174],"class_list":["post-39872","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-releases","tag-bay-area","tag-cca","tag-climate-action","tag-legacy-layout","tag-new-communities","tag-sustainability"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Two More Cities in Solano &amp; Contra Costa Counties Join MCE - Press Release<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mcecleanenergy.org\/de\/two-more-cities-in-solano-contra-costa-counties-join-mce\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Two More Cities in Solano &amp; Contra Costa Counties Join MCE\" \/>\n<meta property=\"og:description\" content=\"Electricity Customers in Pleasant Hill &amp; Vallejo to Gain Choice &amp; Renewable Energy Options in 2021 FOR IMMEDIATE RELEASE November 25, 2019 MCE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mcecleanenergy.org\/de\/two-more-cities-in-solano-contra-costa-counties-join-mce\/\" \/>\n<meta property=\"og:site_name\" content=\"MCE \u2013 Community Choice Energy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mceCleanEnergy\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-25T17:57:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-14T19:05:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/welcome-vallejo-and-pleasant-hill-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rohan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MCECleanEnergy\" \/>\n<meta name=\"twitter:site\" content=\"@MCECleanEnergy\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rohan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/two-more-cities-in-solano-contra-costa-counties-join-mce\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/two-more-cities-in-solano-contra-costa-counties-join-mce\\\/\"},\"author\":{\"name\":\"Rohan\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#\\\/schema\\\/person\\\/8ce2f62799413aaa2b6868dc9b471748\"},\"headline\":\"Two More Cities in Solano &#038; Contra Costa Counties Join MCE\",\"datePublished\":\"2019-11-25T17:57:10+00:00\",\"dateModified\":\"2026-05-14T19:05:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/two-more-cities-in-solano-contra-costa-counties-join-mce\\\/\"},\"wordCount\":679,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/two-more-cities-in-solano-contra-costa-counties-join-mce\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/welcome-vallejo-and-pleasant-hill-2.jpg\",\"keywords\":[\"Bay Area\",\"CCA\",\"climate action\",\"Legacy Layout\",\"New Communities\",\"Sustainability\"],\"articleSection\":[\"Press Releases\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mcecleanenergy.org\\\/two-more-cities-in-solano-contra-costa-counties-join-mce\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/two-more-cities-in-solano-contra-costa-counties-join-mce\\\/\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/two-more-cities-in-solano-contra-costa-counties-join-mce\\\/\",\"name\":\"Two More Cities in Solano & Contra Costa Counties Join MCE - Press Release\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/two-more-cities-in-solano-contra-costa-counties-join-mce\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/two-more-cities-in-solano-contra-costa-counties-join-mce\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/welcome-vallejo-and-pleasant-hill-2.jpg\",\"datePublished\":\"2019-11-25T17:57:10+00:00\",\"dateModified\":\"2026-05-14T19:05:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/two-more-cities-in-solano-contra-costa-counties-join-mce\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mcecleanenergy.org\\\/two-more-cities-in-solano-contra-costa-counties-join-mce\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/two-more-cities-in-solano-contra-costa-counties-join-mce\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/welcome-vallejo-and-pleasant-hill-2.jpg\",\"contentUrl\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/welcome-vallejo-and-pleasant-hill-2.jpg\",\"width\":1440,\"height\":576},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/two-more-cities-in-solano-contra-costa-counties-join-mce\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mcecleanenergy.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Two More Cities in Solano &#038; Contra Costa Counties Join MCE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#website\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/\",\"name\":\"MCE \u2013 Community Choice Energy\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mcecleanenergy.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#organization\",\"name\":\"MCE\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/MCE_Logo_Full-Color_RGB_050324.png\",\"contentUrl\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/MCE_Logo_Full-Color_RGB_050324.png\",\"width\":5001,\"height\":2986,\"caption\":\"MCE\"},\"image\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mceCleanEnergy\\\/\",\"https:\\\/\\\/x.com\\\/MCECleanEnergy\",\"https:\\\/\\\/www.instagram.com\\\/mcecleanenergy\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mcecleanenergy\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/Mcecleanenergy\\\/\",\"https:\\\/\\\/en.wikipedia.org\\\/wiki\\\/Community_Choice_Aggregation#Marin_Clean_Energy\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#\\\/schema\\\/person\\\/8ce2f62799413aaa2b6868dc9b471748\",\"name\":\"Rohan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/08c0249ed3a34e3695a3cb94fc48aa840d636d2ba6af19ac1dd65e5303c3c992?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/08c0249ed3a34e3695a3cb94fc48aa840d636d2ba6af19ac1dd65e5303c3c992?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/08c0249ed3a34e3695a3cb94fc48aa840d636d2ba6af19ac1dd65e5303c3c992?s=96&d=mm&r=g\",\"caption\":\"Rohan\"},\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/de\\\/author\\\/rohan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Zwei weitere St\u00e4dte in den Landkreisen Solano und Contra Costa treten MCE bei \u2013 Pressemitteilung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mcecleanenergy.org\/de\/two-more-cities-in-solano-contra-costa-counties-join-mce\/","og_locale":"de_DE","og_type":"article","og_title":"Two More Cities in Solano & Contra Costa Counties Join MCE","og_description":"Electricity Customers in Pleasant Hill &amp; Vallejo to Gain Choice &amp; Renewable Energy Options in 2021 FOR IMMEDIATE RELEASE November 25, 2019 MCE","og_url":"https:\/\/mcecleanenergy.org\/de\/two-more-cities-in-solano-contra-costa-counties-join-mce\/","og_site_name":"MCE \u2013 Community Choice Energy","article_publisher":"https:\/\/www.facebook.com\/mceCleanEnergy\/","article_published_time":"2019-11-25T17:57:10+00:00","article_modified_time":"2026-05-14T19:05:54+00:00","og_image":[{"width":1440,"height":576,"url":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/welcome-vallejo-and-pleasant-hill-2.jpg","type":"image\/jpeg"}],"author":"Rohan","twitter_card":"summary_large_image","twitter_creator":"@MCECleanEnergy","twitter_site":"@MCECleanEnergy","twitter_misc":{"Verfasst von":"Rohan","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mcecleanenergy.org\/two-more-cities-in-solano-contra-costa-counties-join-mce\/#article","isPartOf":{"@id":"https:\/\/mcecleanenergy.org\/two-more-cities-in-solano-contra-costa-counties-join-mce\/"},"author":{"name":"Rohan","@id":"https:\/\/mcecleanenergy.org\/#\/schema\/person\/8ce2f62799413aaa2b6868dc9b471748"},"headline":"Two More Cities in Solano &#038; Contra Costa Counties Join MCE","datePublished":"2019-11-25T17:57:10+00:00","dateModified":"2026-05-14T19:05:54+00:00","mainEntityOfPage":{"@id":"https:\/\/mcecleanenergy.org\/two-more-cities-in-solano-contra-costa-counties-join-mce\/"},"wordCount":679,"commentCount":0,"publisher":{"@id":"https:\/\/mcecleanenergy.org\/#organization"},"image":{"@id":"https:\/\/mcecleanenergy.org\/two-more-cities-in-solano-contra-costa-counties-join-mce\/#primaryimage"},"thumbnailUrl":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/welcome-vallejo-and-pleasant-hill-2.jpg","keywords":["Bay Area","CCA","climate action","Legacy Layout","New Communities","Sustainability"],"articleSection":["Press Releases"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mcecleanenergy.org\/two-more-cities-in-solano-contra-costa-counties-join-mce\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mcecleanenergy.org\/two-more-cities-in-solano-contra-costa-counties-join-mce\/","url":"https:\/\/mcecleanenergy.org\/two-more-cities-in-solano-contra-costa-counties-join-mce\/","name":"Zwei weitere St\u00e4dte in den Landkreisen Solano und Contra Costa treten MCE bei \u2013 Pressemitteilung","isPartOf":{"@id":"https:\/\/mcecleanenergy.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mcecleanenergy.org\/two-more-cities-in-solano-contra-costa-counties-join-mce\/#primaryimage"},"image":{"@id":"https:\/\/mcecleanenergy.org\/two-more-cities-in-solano-contra-costa-counties-join-mce\/#primaryimage"},"thumbnailUrl":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/welcome-vallejo-and-pleasant-hill-2.jpg","datePublished":"2019-11-25T17:57:10+00:00","dateModified":"2026-05-14T19:05:54+00:00","breadcrumb":{"@id":"https:\/\/mcecleanenergy.org\/two-more-cities-in-solano-contra-costa-counties-join-mce\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mcecleanenergy.org\/two-more-cities-in-solano-contra-costa-counties-join-mce\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/mcecleanenergy.org\/two-more-cities-in-solano-contra-costa-counties-join-mce\/#primaryimage","url":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/welcome-vallejo-and-pleasant-hill-2.jpg","contentUrl":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/welcome-vallejo-and-pleasant-hill-2.jpg","width":1440,"height":576},{"@type":"BreadcrumbList","@id":"https:\/\/mcecleanenergy.org\/two-more-cities-in-solano-contra-costa-counties-join-mce\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mcecleanenergy.org\/"},{"@type":"ListItem","position":2,"name":"Two More Cities in Solano &#038; Contra Costa Counties Join MCE"}]},{"@type":"WebSite","@id":"https:\/\/mcecleanenergy.org\/#website","url":"https:\/\/mcecleanenergy.org\/","name":"MCE - Energie nach Wahl der Gemeinde","description":"","publisher":{"@id":"https:\/\/mcecleanenergy.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mcecleanenergy.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/mcecleanenergy.org\/#organization","name":"MCE","url":"https:\/\/mcecleanenergy.org\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/mcecleanenergy.org\/#\/schema\/logo\/image\/","url":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/MCE_Logo_Full-Color_RGB_050324.png","contentUrl":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/MCE_Logo_Full-Color_RGB_050324.png","width":5001,"height":2986,"caption":"MCE"},"image":{"@id":"https:\/\/mcecleanenergy.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mceCleanEnergy\/","https:\/\/x.com\/MCECleanEnergy","https:\/\/www.instagram.com\/mcecleanenergy\/","https:\/\/www.linkedin.com\/company\/mcecleanenergy\/","https:\/\/www.youtube.com\/c\/Mcecleanenergy\/","https:\/\/en.wikipedia.org\/wiki\/Community_Choice_Aggregation#Marin_Clean_Energy"]},{"@type":"Person","@id":"https:\/\/mcecleanenergy.org\/#\/schema\/person\/8ce2f62799413aaa2b6868dc9b471748","name":"Rohan","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/08c0249ed3a34e3695a3cb94fc48aa840d636d2ba6af19ac1dd65e5303c3c992?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/08c0249ed3a34e3695a3cb94fc48aa840d636d2ba6af19ac1dd65e5303c3c992?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/08c0249ed3a34e3695a3cb94fc48aa840d636d2ba6af19ac1dd65e5303c3c992?s=96&d=mm&r=g","caption":"Rohan"},"url":"https:\/\/mcecleanenergy.org\/de\/author\/rohan\/"}]}},"_links":{"self":[{"href":"https:\/\/mcecleanenergy.org\/de\/wp-json\/wp\/v2\/posts\/39872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mcecleanenergy.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mcecleanenergy.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mcecleanenergy.org\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mcecleanenergy.org\/de\/wp-json\/wp\/v2\/comments?post=39872"}],"version-history":[{"count":1,"href":"https:\/\/mcecleanenergy.org\/de\/wp-json\/wp\/v2\/posts\/39872\/revisions"}],"predecessor-version":[{"id":83361,"href":"https:\/\/mcecleanenergy.org\/de\/wp-json\/wp\/v2\/posts\/39872\/revisions\/83361"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mcecleanenergy.org\/de\/wp-json\/wp\/v2\/media\/39873"}],"wp:attachment":[{"href":"https:\/\/mcecleanenergy.org\/de\/wp-json\/wp\/v2\/media?parent=39872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mcecleanenergy.org\/de\/wp-json\/wp\/v2\/categories?post=39872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mcecleanenergy.org\/de\/wp-json\/wp\/v2\/tags?post=39872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}