{"id":85503,"date":"2026-06-25T09:00:00","date_gmt":"2026-06-25T16:00:00","guid":{"rendered":"https:\/\/mcecleanenergy.org\/?p=85503"},"modified":"2026-06-24T15:20:00","modified_gmt":"2026-06-24T22:20:00","slug":"mce-partners-bring-clean-energy-programs-closer-to-home","status":"publish","type":"post","link":"https:\/\/mcecleanenergy.org\/de\/mce-partners-bring-clean-energy-programs-closer-to-home\/","title":{"rendered":"MCE Partners bringen Programme f\u00fcr saubere Energie n\u00e4her an die B\u00fcrger\u00a0"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"85503\" class=\"elementor elementor-85503\" data-elementor-post-type=\"post\">\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-d967f92 e-flex e-con-boxed e-con e-parent\" data-id=\"d967f92\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6e766cc elementor-widget elementor-widget-text-editor\" data-id=\"6e766cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Das Community Partnership Program von MCE hilft dabei, Menschen \u00fcber Organisationen, denen sie bereits vertrauen, mit Programmen f\u00fcr saubere Energie zu verbinden. Im Jahr 2025 finanzierte MCE lokale Partner, um Informationen \u00fcber das Programm direkt an Einwohner, kleine Unternehmen, Auftragnehmer und Gemeindemitglieder in unserem gesamten Servicegebiet zu bringen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-d0c7c0d e-flex e-con-boxed e-con e-parent\" data-id=\"d0c7c0d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b828b19 elementor-widget elementor-widget-text-editor\" data-id=\"b828b19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Was das Programm 2025 finanzierte<\/h4><p>F\u00fcr das Programmjahr 2025 lud MCE gemeinn\u00fctzige Organisationen, \u00f6ffentliche Einrichtungen und b\u00fcrgernahe Organisationen dazu ein, Projekte zur \u00d6ffentlichkeitsarbeit vorzuschlagen, die das Verst\u00e4ndnis und den Zugang zu den MCE-Programmen erleichtern sollen. Ausgew\u00e4hlte Partner konnten bis zu $30.000 erhalten, um \u00d6ffentlichkeitsarbeit in Bereichen wie Kosteneinsparungen bei Stromrechnungen, energetische Sanierungen kleiner Unternehmen, Wege in die Arbeitswelt, Elektrifizierung von Geb\u00e4uden, umweltfreundlicher Verkehr sowie die Einbindung einkommensschwacher und unterversorgter Gemeinden zu unterst\u00fctzen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-ae78577 e-flex e-con-boxed e-con e-parent\" data-id=\"ae78577\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-855172f elementor-widget elementor-widget-text-editor\" data-id=\"855172f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Lernen Sie die Community-Partner 2025 kennen<\/h4><p>MCE vergab im Jahr 2025 Auftr\u00e4ge im Gesamtwert von $100.000 auf sechs Vertr\u00e4ge verteilt. Jeder Partner brachte fundierte lokale Kontakte und einen eigenen Ansatz zur Einbindung der Bev\u00f6lkerung mit.<\/p><ul><li><strong>Canal Alliance (San Rafael, Marin County)<\/strong> teilte zweisprachige Informationen zu Rechnungsersparnissen, bot individuelle Schulungen an und half Kunden bei der Anmeldung zu MCE-Programmen.<\/li><li><strong>Nord-Marin-Gemeinschaftsdienste (Marin County)<\/strong> erreichten die Bewohner durch Pr\u00e4sentationen, die Arbeit in der Lebensmittelausgabe, Fallmanagement und zweisprachige Materialien.<\/li><li><strong>Stadt Pinole<\/strong> Unterst\u00fctzungsarbeit f\u00fcr Arbeitskr\u00e4fte, Schulungen f\u00fcr Auftragnehmer und Unternehmen, Workshops und Gemeinschaftsveranstaltungen.<\/li><li><strong>Wirtschaftsf\u00f6rderungsgesellschaft San Pablo<\/strong> kleine Unternehmen mit dem \u201eSmall Business Energy Advantage\u201c-Programm von MCE vernetzt.<\/li><li><strong>Vallejo Main Street<\/strong> lokale Gesch\u00e4ftsstra\u00dfen erkundet und M\u00f6glichkeiten zur Energieeinsparung f\u00fcr Kleinunternehmen beworben.<\/li><li><strong>Solano Wirtschafts-Entwicklungsgesellschaft<\/strong> zur Sensibilisierung f\u00fcr MCE-Programme durch Gesch\u00e4fts- und Gemeinschaftsveranstaltungen in Solano County beigetragen.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-4be3d60 e-flex e-con-boxed e-con e-parent\" data-id=\"4be3d60\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8deeb78 elementor-widget elementor-widget-text-editor\" data-id=\"8deeb78\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Was Partner taten<\/h4><p>Partner mit Menschen dort, wo sie waren: in Lebensmittelausgaben, auf Gemeinschaftsmessen, in Workshops, in Gesch\u00e4ftsvierteln, bei Fallmanagementterminen und lokalen Veranstaltungen. Sie beantworteten Fragen, teilten Materialien aus, erkl\u00e4rten Programme und halfen Kunden, den n\u00e4chsten Schritt zu tun.<\/p><p>Einige Partner konzentrierten sich auf allgemeine Bildung und Einsparungen. Andere konzentrierten sich auf gezielte Ansprache von Kleinunternehmen, Kompetenzentwicklung, Schulung von Handwerkern oder Elektrifizierung von Geb\u00e4uden. Gemeinsam trugen ihre Bem\u00fchungen dazu bei, die MCE-Programme sichtbarer, zug\u00e4nglicher und umsetzbarer zu machen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-335fadd e-flex e-con-boxed e-con e-parent\" data-id=\"335fadd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0321533 elementor-widget elementor-widget-text-editor\" data-id=\"0321533\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Ergebnisse 2025 im \u00dcberblick<\/h4><p>Die Ergebnisse zeigen die Wirkung der lokalen \u00d6ffentlichkeitsarbeit. Im Jahr 2025 halfen Partner des Community Partnership Program MCE, Menschen online, in Printmedien und pers\u00f6nlich zu erreichen.<\/p><ul><li><strong>$100,000<\/strong> an Gemeindepartner verliehen<\/li><li><strong>6<\/strong> abgeschlossene Vertr\u00e4ge<\/li><li><strong>79,721<\/strong> erreichte Gesamtkunden<ul><li><strong>4,266<\/strong> Kunden, die pers\u00f6nlich erreicht wurden<\/li><li><strong>18,651<\/strong> Menschen, die online erreicht wurden<\/li><li><strong>58,089<\/strong> Zielgruppe, die durch Print-Werbung erreicht wird<\/li><\/ul><\/li><li><strong>1,539<\/strong> auf Spanisch verbreitete Materialien<\/li><li><strong>31<\/strong> Unterst\u00fctzte Gemeinschaftsveranstaltungen<\/li><li><strong>12<\/strong> Pr\u00e4sentationen geliefert, darunter <strong>3<\/strong> en espa\u00f1ol<\/li><li><strong>90<\/strong> Kunden, die in MCE-Programme eingeschrieben sind<\/li><\/ul><p><br \/>Die Partner trugen zudem dazu bei, die Aktivit\u00e4ten von MCE im Bereich der Kleinunternehmen und der Arbeitsvermittlung auszuweiten: Sie kn\u00fcpften 1.602 Kontakte zu Kleinunternehmen, generierten 51 Small Business Energy Advantage-Empfehlungen, unterst\u00fctzten drei realisierte Projekte, erreichten 500 Menschen im Rahmen von Ma\u00dfnahmen zur Arbeitsvermittlung und sorgten daf\u00fcr, dass 70 Teilnehmer an Workshops teilnahmen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-b94da17 e-flex e-con-boxed e-con e-parent\" data-id=\"b94da17\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f5a9047 elementor-widget elementor-widget-text-editor\" data-id=\"f5a9047\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Warum es funktionierte<\/h4><p>Die st\u00e4rkste Reichweite kam von vertrauensw\u00fcrdigen Botschaftern. Community-Partner hatten bereits Beziehungen zu den Personen, die MCE erreichen wollte, was die Gespr\u00e4che pers\u00f6nlicher, n\u00fctzlicher und effektiver machte.<\/p><p>Partner trugen auch dazu bei, die Bed\u00fcrfnisse der Kunden am besten zu identifizieren: einfache Erkl\u00e4rungen, klare n\u00e4chste Schritte, zweisprachige Materialien und die Zusicherung, dass Programme f\u00fcr Mieter, Einwandererhaushalte, kleine Unternehmen und andere, die sich m\u00f6glicherweise nicht immer in herk\u00f6mmlichen Outreach-Ma\u00dfnahmen wiederfinden, geeignet sein k\u00f6nnen.<\/p><p>Die wichtigste Lektion war klar: Aufkl\u00e4rungsarbeit funktioniert am besten, wenn sie lokal, praktisch und auf Vertrauen aufgebaut ist.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-99cc03e e-flex e-con-boxed e-con e-parent\" data-id=\"99cc03e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2fc4064 elementor-widget elementor-widget-text-editor\" data-id=\"2fc4064\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Blick nach vorn auf 2026<\/h4><p>MCE hat das Community Partnership Program Ende 2025 f\u00fcr die Arbeit im Kalenderjahr 2026 wieder er\u00f6ffnet. Die n\u00e4chste Runde verfolgt weiterhin dasselbe Ziel: mehr Kunden sollen durch vertrauensw\u00fcrdige lokale Partner MCE-Programme kennenlernen und von ihnen profitieren.<\/p><p>MCE w\u00e4hlte drei Partner f\u00fcr die Finanzierung im Jahr 2026 aus, wobei jede Organisation vertrauensvolle Beziehungen zu Gemeinden mitbrachte und einen klaren Plan zur Ausweitung der Reichweite verfolgte.<\/p><ul><li><strong>Gemeindedienste Nord Marin<\/strong> \u2014 Es wurden $30.000 bewilligt, um die erfolgreiche Arbeit ab 2025 fortzusetzen, insbesondere die \u00d6ffentlichkeitsarbeit im Rahmen des \u201ePromotoras\u201c-Programms.<\/li><li><strong>San Pablo EDC<\/strong> \u2014 Es wurden $12.500 bewilligt, um die erfolgreiche Arbeit aus dem Kalenderjahr 2025 fortzusetzen.<\/li><li><strong>Puertas Abiertas (Napa County)<\/strong> \u2014 Es wurden $30.000 bewilligt, um Aufkl\u00e4rungsarbeit speziell in der lateinamerikanischen Gemeinschaft in Napa zu leisten, wobei der Schwerpunkt auf der Einf\u00fchrung von Energieeffizienzprogrammen und Programmen zur Senkung der Energiekosten durch \u201ePromotoras\u201c liegt.<\/li><\/ul><p><br \/>MCE w\u00fcrdigte zudem den \u00fcberzeugenden Antrag der UpValley Family Centers (Calistoga, Napa County) mit einem F\u00f6rderzuschuss in H\u00f6he von $13.000 zur Unterst\u00fctzung von Aufkl\u00e4rungsma\u00dfnahmen in der Bev\u00f6lkerung hinsichtlich der Einsparung von Stromkosten und allgemeiner Informationen \u00fcber MCE durch Promotoras in der Region Upper Napa Valley.<\/p><p>Wir freuen uns, Neuigkeiten \u00fcber die Erfolge des Programms 2026 im Jahr 2027 mit Ihnen zu teilen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>MCE\u2019s Community Partnership Program helps connect people with clean energy programs through the organizations they already know and trust. In 2025, MCE funded local partners to bring program information directly [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":85504,"comment_status":"closed","ping_status":"open","sticky":false,"template":"elementor_theme","format":"standard","meta":{"_acf_changed":false,"_searchwp_excluded":"","footnotes":""},"categories":[822,558],"tags":[],"class_list":["post-85503","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energy-bill-savings","category-in-the-community"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>MCE Partners Bring Clean Energy Programs Closer to Home\u00a0 - MCE Blog<\/title>\n<meta name=\"description\" content=\"MCE\u2019s Community Partnership Program helps connect people with clean energy programs through the organizations they already know and trust.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mcecleanenergy.org\/de\/mce-partners-bring-clean-energy-programs-closer-to-home\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MCE Partners Bring Clean Energy Programs Closer to Home\u00a0\" \/>\n<meta property=\"og:description\" content=\"MCE\u2019s Community Partnership Program helps connect people with clean energy programs through the organizations they already know and trust. In 2025, MCE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mcecleanenergy.org\/de\/mce-partners-bring-clean-energy-programs-closer-to-home\/\" \/>\n<meta property=\"og:site_name\" content=\"MCE \u2013 Community Choice Energy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mceCleanEnergy\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-25T16:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2026\/06\/community-partnership-program-results-blog.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1180\" \/>\n\t<meta property=\"og:image:height\" content=\"475\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Debbie Lamb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MCECleanEnergy\" \/>\n<meta name=\"twitter:site\" content=\"@MCECleanEnergy\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Debbie Lamb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/mce-partners-bring-clean-energy-programs-closer-to-home\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/mce-partners-bring-clean-energy-programs-closer-to-home\\\/\"},\"author\":{\"name\":\"Debbie Lamb\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#\\\/schema\\\/person\\\/529ce2d4ac862fbb09c6c0a9b0b952cd\"},\"headline\":\"MCE Partners Bring Clean Energy Programs Closer to Home\u00a0\",\"datePublished\":\"2026-06-25T16:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/mce-partners-bring-clean-energy-programs-closer-to-home\\\/\"},\"wordCount\":659,\"publisher\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/mce-partners-bring-clean-energy-programs-closer-to-home\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/community-partnership-program-results-blog.png\",\"articleSection\":[\"Energy Bill Savings\",\"In the Community\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/mce-partners-bring-clean-energy-programs-closer-to-home\\\/\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/mce-partners-bring-clean-energy-programs-closer-to-home\\\/\",\"name\":\"MCE Partners Bring Clean Energy Programs Closer to Home\u00a0 - MCE Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/mce-partners-bring-clean-energy-programs-closer-to-home\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/mce-partners-bring-clean-energy-programs-closer-to-home\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/community-partnership-program-results-blog.png\",\"datePublished\":\"2026-06-25T16:00:00+00:00\",\"description\":\"MCE\u2019s Community Partnership Program helps connect people with clean energy programs through the organizations they already know and trust.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/mce-partners-bring-clean-energy-programs-closer-to-home\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mcecleanenergy.org\\\/mce-partners-bring-clean-energy-programs-closer-to-home\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/mce-partners-bring-clean-energy-programs-closer-to-home\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/community-partnership-program-results-blog.png\",\"contentUrl\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/community-partnership-program-results-blog.png\",\"width\":1180,\"height\":475,\"caption\":\"MCE Partners Bring Clean Energy Programs Closer to Home\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/mce-partners-bring-clean-energy-programs-closer-to-home\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mcecleanenergy.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MCE Partners Bring Clean Energy Programs Closer to Home\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#website\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/\",\"name\":\"MCE \u2013 Community Choice Energy\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mcecleanenergy.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#organization\",\"name\":\"MCE\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/MCE_Logo_Full-Color_RGB_050324.png\",\"contentUrl\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/MCE_Logo_Full-Color_RGB_050324.png\",\"width\":5001,\"height\":2986,\"caption\":\"MCE\"},\"image\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mceCleanEnergy\\\/\",\"https:\\\/\\\/x.com\\\/MCECleanEnergy\",\"https:\\\/\\\/www.instagram.com\\\/mcecleanenergy\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mcecleanenergy\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/Mcecleanenergy\\\/\",\"https:\\\/\\\/en.wikipedia.org\\\/wiki\\\/Community_Choice_Aggregation#Marin_Clean_Energy\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#\\\/schema\\\/person\\\/529ce2d4ac862fbb09c6c0a9b0b952cd\",\"name\":\"Debbie Lamb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c439b0a089c2fd256f9db2b902d716abcbed16d561521cc3bbf4dfa4a1cf2b5a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c439b0a089c2fd256f9db2b902d716abcbed16d561521cc3bbf4dfa4a1cf2b5a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c439b0a089c2fd256f9db2b902d716abcbed16d561521cc3bbf4dfa4a1cf2b5a?s=96&d=mm&r=g\",\"caption\":\"Debbie Lamb\"},\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/de\\\/author\\\/debbie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"MCE Partners Bring Clean Energy Programs Closer to Home\u00a0 - MCE Blog","description":"MCE\u2019s Community Partnership Program helps connect people with clean energy programs through the organizations they already know and trust.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mcecleanenergy.org\/de\/mce-partners-bring-clean-energy-programs-closer-to-home\/","og_locale":"de_DE","og_type":"article","og_title":"MCE Partners Bring Clean Energy Programs Closer to Home\u00a0","og_description":"MCE\u2019s Community Partnership Program helps connect people with clean energy programs through the organizations they already know and trust. In 2025, MCE","og_url":"https:\/\/mcecleanenergy.org\/de\/mce-partners-bring-clean-energy-programs-closer-to-home\/","og_site_name":"MCE \u2013 Community Choice Energy","article_publisher":"https:\/\/www.facebook.com\/mceCleanEnergy\/","article_published_time":"2026-06-25T16:00:00+00:00","og_image":[{"width":1180,"height":475,"url":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2026\/06\/community-partnership-program-results-blog.png","type":"image\/png"}],"author":"Debbie Lamb","twitter_card":"summary_large_image","twitter_creator":"@MCECleanEnergy","twitter_site":"@MCECleanEnergy","twitter_misc":{"Verfasst von":"Debbie Lamb","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mcecleanenergy.org\/mce-partners-bring-clean-energy-programs-closer-to-home\/#article","isPartOf":{"@id":"https:\/\/mcecleanenergy.org\/mce-partners-bring-clean-energy-programs-closer-to-home\/"},"author":{"name":"Debbie Lamb","@id":"https:\/\/mcecleanenergy.org\/#\/schema\/person\/529ce2d4ac862fbb09c6c0a9b0b952cd"},"headline":"MCE Partners Bring Clean Energy Programs Closer to Home\u00a0","datePublished":"2026-06-25T16:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/mcecleanenergy.org\/mce-partners-bring-clean-energy-programs-closer-to-home\/"},"wordCount":659,"publisher":{"@id":"https:\/\/mcecleanenergy.org\/#organization"},"image":{"@id":"https:\/\/mcecleanenergy.org\/mce-partners-bring-clean-energy-programs-closer-to-home\/#primaryimage"},"thumbnailUrl":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2026\/06\/community-partnership-program-results-blog.png","articleSection":["Energy Bill Savings","In the Community"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/mcecleanenergy.org\/mce-partners-bring-clean-energy-programs-closer-to-home\/","url":"https:\/\/mcecleanenergy.org\/mce-partners-bring-clean-energy-programs-closer-to-home\/","name":"MCE Partners Bring Clean Energy Programs Closer to Home\u00a0 - MCE Blog","isPartOf":{"@id":"https:\/\/mcecleanenergy.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mcecleanenergy.org\/mce-partners-bring-clean-energy-programs-closer-to-home\/#primaryimage"},"image":{"@id":"https:\/\/mcecleanenergy.org\/mce-partners-bring-clean-energy-programs-closer-to-home\/#primaryimage"},"thumbnailUrl":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2026\/06\/community-partnership-program-results-blog.png","datePublished":"2026-06-25T16:00:00+00:00","description":"MCE\u2019s Community Partnership Program helps connect people with clean energy programs through the organizations they already know and trust.","breadcrumb":{"@id":"https:\/\/mcecleanenergy.org\/mce-partners-bring-clean-energy-programs-closer-to-home\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mcecleanenergy.org\/mce-partners-bring-clean-energy-programs-closer-to-home\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/mcecleanenergy.org\/mce-partners-bring-clean-energy-programs-closer-to-home\/#primaryimage","url":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2026\/06\/community-partnership-program-results-blog.png","contentUrl":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2026\/06\/community-partnership-program-results-blog.png","width":1180,"height":475,"caption":"MCE Partners Bring Clean Energy Programs Closer to Home"},{"@type":"BreadcrumbList","@id":"https:\/\/mcecleanenergy.org\/mce-partners-bring-clean-energy-programs-closer-to-home\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mcecleanenergy.org\/"},{"@type":"ListItem","position":2,"name":"MCE Partners Bring Clean Energy Programs Closer to Home\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/mcecleanenergy.org\/#website","url":"https:\/\/mcecleanenergy.org\/","name":"MCE - Energie nach Wahl der Gemeinde","description":"","publisher":{"@id":"https:\/\/mcecleanenergy.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mcecleanenergy.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/mcecleanenergy.org\/#organization","name":"MCE","url":"https:\/\/mcecleanenergy.org\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/mcecleanenergy.org\/#\/schema\/logo\/image\/","url":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/MCE_Logo_Full-Color_RGB_050324.png","contentUrl":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/MCE_Logo_Full-Color_RGB_050324.png","width":5001,"height":2986,"caption":"MCE"},"image":{"@id":"https:\/\/mcecleanenergy.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mceCleanEnergy\/","https:\/\/x.com\/MCECleanEnergy","https:\/\/www.instagram.com\/mcecleanenergy\/","https:\/\/www.linkedin.com\/company\/mcecleanenergy\/","https:\/\/www.youtube.com\/c\/Mcecleanenergy\/","https:\/\/en.wikipedia.org\/wiki\/Community_Choice_Aggregation#Marin_Clean_Energy"]},{"@type":"Person","@id":"https:\/\/mcecleanenergy.org\/#\/schema\/person\/529ce2d4ac862fbb09c6c0a9b0b952cd","name":"Debbie Lamb","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/c439b0a089c2fd256f9db2b902d716abcbed16d561521cc3bbf4dfa4a1cf2b5a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c439b0a089c2fd256f9db2b902d716abcbed16d561521cc3bbf4dfa4a1cf2b5a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c439b0a089c2fd256f9db2b902d716abcbed16d561521cc3bbf4dfa4a1cf2b5a?s=96&d=mm&r=g","caption":"Debbie Lamb"},"url":"https:\/\/mcecleanenergy.org\/de\/author\/debbie\/"}]}},"_links":{"self":[{"href":"https:\/\/mcecleanenergy.org\/de\/wp-json\/wp\/v2\/posts\/85503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mcecleanenergy.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mcecleanenergy.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mcecleanenergy.org\/de\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/mcecleanenergy.org\/de\/wp-json\/wp\/v2\/comments?post=85503"}],"version-history":[{"count":28,"href":"https:\/\/mcecleanenergy.org\/de\/wp-json\/wp\/v2\/posts\/85503\/revisions"}],"predecessor-version":[{"id":85552,"href":"https:\/\/mcecleanenergy.org\/de\/wp-json\/wp\/v2\/posts\/85503\/revisions\/85552"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mcecleanenergy.org\/de\/wp-json\/wp\/v2\/media\/85504"}],"wp:attachment":[{"href":"https:\/\/mcecleanenergy.org\/de\/wp-json\/wp\/v2\/media?parent=85503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mcecleanenergy.org\/de\/wp-json\/wp\/v2\/categories?post=85503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mcecleanenergy.org\/de\/wp-json\/wp\/v2\/tags?post=85503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}