{"id":40082,"date":"2021-03-16T09:57:57","date_gmt":"2021-03-16T16:57:57","guid":{"rendered":"https:\/\/mcecleanenergy.org\/energy-expert-microgrids\/"},"modified":"2024-06-01T15:56:45","modified_gmt":"2024-06-01T22:56:45","slug":"energy-expert-microgrids","status":"publish","type":"post","link":"https:\/\/mcecleanenergy.org\/es\/energy-expert-microgrids\/","title":{"rendered":"Experto en energ\u00eda: Microrredes"},"content":{"rendered":"<h5><strong>La Serie de Expertos en Energ\u00eda de MCE profundiza en temas energ\u00e9ticos m\u00e1s complejos, como el desarrollo de la curva de pato y los entresijos del Net Energy Metering. Entre bastidores con nuestro <a href=\"https:\/\/mcecleanenergy.org\/es\/category\/energy-expert\/\">Experto en energ\u00eda<\/a> o lea m\u00e1s en nuestra <\/strong><a href=\"https:\/\/mcecleanenergy.org\/es\/category\/energy-101\/\"><strong>Serie Energ\u00eda 101<\/strong><\/a>.<\/h5>\n<p>A medida que aumentan los incendios forestales y los fen\u00f3menos meteorol\u00f3gicos extremos, m\u00e1s clientes buscan soluciones que ofrezcan una mayor resistencia energ\u00e9tica. La resistencia energ\u00e9tica es cualquier sistema de energ\u00eda que permite a los clientes acceder a la electricidad incluso cuando la red el\u00e9ctrica no est\u00e1 operativa, como durante una tormenta, un incendio forestal o un corte de suministro de seguridad p\u00fablica. La resiliencia energ\u00e9tica puede abordarse de muchas maneras: con un panel solar y una bater\u00eda en casa, con una bater\u00eda de reserva port\u00e1til que se carga cuando hay electricidad o con un gran sistema conocido como microrred.<\/p>\n<p>Las microrredes son fuentes locales de generaci\u00f3n y almacenamiento de energ\u00eda que pueden desconectarse de la red el\u00e9ctrica general para suministrar energ\u00eda a una sola instalaci\u00f3n o a un grupo de edificios o viviendas. Cuando la red el\u00e9ctrica principal falla, las microrredes permiten a los edificios conectados mantener la energ\u00eda. Las microrredes son m\u00e1s frecuentes en instalaciones tipo campus, como centros de investigaci\u00f3n o universidades.<\/p>\n<p><strong>\u00bfC\u00f3mo funciona una microrred?<\/strong><\/p>\n<p>Una red el\u00e9ctrica tradicional conecta un gran n\u00famero de instalaciones a diversas fuentes centralizadas de generaci\u00f3n de energ\u00eda a trav\u00e9s de l\u00edneas de transmisi\u00f3n el\u00e9ctrica de larga distancia. La energ\u00eda se genera y transporta a trav\u00e9s de estas l\u00edneas hasta donde se necesita. Este sistema centralizado ha beneficiado a los clientes al proporcionarles acceso a grandes formas de generaci\u00f3n el\u00e9ctrica de bajo coste. Sin embargo, cuando la red se cae, todos los que est\u00e1n conectados a ella se quedan sin electricidad. Puede obtener m\u00e1s informaci\u00f3n sobre el funcionamiento de los servicios de electricidad en nuestro <a href=\"https:\/\/mcecleanenergy.org\/es\/news\/energy-101-energy-basics\/\">Blog sobre energ\u00eda b\u00e1sica<\/a>.<\/p>\n<p>En cambio, las microrredes funcionan en t\u00e1ndem con la red el\u00e9ctrica tradicional, pero pueden aislarse y funcionar por s\u00ed solas si la red el\u00e9ctrica principal se cae. Esta energ\u00eda alternativa requiere fuentes de generaci\u00f3n locales, como la energ\u00eda solar combinada con el almacenamiento en bater\u00edas. Los recursos que se utilizan para crear una microrred pueden variar, pero lo que las hace \u00fanicas es su capacidad para proporcionar energ\u00eda de reserva a las instalaciones conectadas, a menudo utilizando fuentes de generaci\u00f3n limpias.<\/p>\n<p><strong>\u00bfCu\u00e1nto consume una microrred?<\/strong><\/p>\n<p>El tama\u00f1o de una microrred puede variar significativamente y puede ser peque\u00f1a para alimentar una sola instalaci\u00f3n o mucho mayor para incluir todo un campus o un barrio. Una microrred no se define por su tama\u00f1o, sino por su capacidad para aislarse de la red y sus fuentes de generaci\u00f3n localizadas que suministran energ\u00eda a toda la zona que cubren. Las microrredes suelen utilizarse en zonas donde un corte de electricidad podr\u00eda perjudicar a quienes utilizan las instalaciones o el trabajo que all\u00ed se realiza, como centros de investigaci\u00f3n, bases militares, operaciones de emergencia (comisar\u00edas y parques de bomberos) y hospitales.<\/p>\n<p>El tiempo que una microrred puede funcionar independientemente de la red el\u00e9ctrica principal depende del tipo y el tama\u00f1o de la generaci\u00f3n y de los recursos de almacenamiento de energ\u00eda que se utilicen. Si el sistema se dise\u00f1a adecuadamente, una microrred puede funcionar durante largos periodos de tiempo: d\u00edas, semanas o incluso m\u00e1s.<\/p>\n<p><strong>\u00bfCu\u00e1les son las ventajas de las microrredes?<\/strong><\/p>\n<ul>\n<li><strong>Resiliencia energ\u00e9tica:<\/strong> El beneficio m\u00e1s notable de las microrredes es la capacidad de mantener la energ\u00eda durante un corte de la red, de modo que las poblaciones vulnerables que necesitan acceso a la electricidad puedan permanecer en sus hogares. Ejemplos de poblaciones vulnerables son las personas que dependen de la electricidad para necesidades m\u00e9dicas o de vida independiente y las que no pueden permitirse un traslado, ni siquiera temporal. La resistencia energ\u00e9tica tambi\u00e9n es importante para las peque\u00f1as empresas que pueden perder ingresos durante un apag\u00f3n debido a la disminuci\u00f3n de clientes o a la falta de refrigeraci\u00f3n para los productos perecederos. Sea cual sea la circunstancia, aumentar la resiliencia energ\u00e9tica ayuda a mantener a la gente segura en sus hogares y reduce la carga econ\u00f3mica.<\/li>\n<li><strong>Ahorro de costes energ\u00e9ticos:<\/strong> La naturaleza de las microrredes requiere generaci\u00f3n local, como la solar, que est\u00e1 disponible cuando brilla el sol, no s\u00f3lo durante un apag\u00f3n. La generaci\u00f3n solar puede reducir los costes energ\u00e9ticos al disminuir la cantidad de electricidad que se compra a la red. Las microrredes son beneficiosas en grandes instalaciones con facturas de electricidad elevadas y en comunidades desatendidas, donde los costes de electricidad suelen representar un porcentaje desproporcionadamente alto de los gastos mensuales.<\/li>\n<li><strong>Energ\u00eda limpia:<\/strong> Las microrredes funcionan utilizando energ\u00edas limpias, como la solar o la e\u00f3lica, combinadas con almacenamiento de energ\u00eda. La energ\u00eda limpia es el mejor recurso para la generaci\u00f3n localizada porque no produce contaminaci\u00f3n atmosf\u00e9rica. Un mayor uso de energ\u00eda limpia no s\u00f3lo es bueno para nuestro planeta, sino tambi\u00e9n para nuestra salud. La reducci\u00f3n de las part\u00edculas en el aire puede ayudar a reducir las tasas de asma infantil y otras enfermedades respiratorias.<\/li>\n<li><strong>Independencia energ\u00e9tica:<\/strong> Otro beneficio notable de una microrred es la capacidad de controlar el suministro el\u00e9ctrico. La independencia energ\u00e9tica es un movimiento creciente que ayuda a las comunidades a recuperar el control de su impacto clim\u00e1tico y su salud futura. Utilizando una microrred, una comunidad o instalaci\u00f3n puede controlar sus facturas de energ\u00eda, el tipo de energ\u00eda que utiliza y las emisiones asociadas a su consumo el\u00e9ctrico.<\/li>\n<\/ul>\n<p><strong>\u00bfC\u00f3mo conseguir una microrred en mi comunidad?<\/strong><\/p>\n<p>El proceso de construcci\u00f3n de una microrred puede ser complicado y costoso. A principios de 2021, la Comisi\u00f3n de Servicios P\u00fablicos de California emiti\u00f3 una decisi\u00f3n sobre el desarrollo de microrredes en el estado de California. Esta decisi\u00f3n inclu\u00eda la creaci\u00f3n de un Programa de Incentivos para Microrredes de $200 millones que permite que las instalaciones cr\u00edticas propiedad de organismos p\u00fablicos y situadas en propiedades adyacentes se suministren energ\u00eda entre s\u00ed durante cortes en la red. Estos interesantes cambios permiten la creaci\u00f3n de m\u00e1s centros de resiliencia de microrredes, que pueden proporcionar recursos a los clientes vulnerables durante los cortes de electricidad.<\/p>\n<p>Con el tiempo, es probable que las microrredes se conviertan en una parte mucho mayor de nuestro panorama energ\u00e9tico. MCE est\u00e1 trabajando diligentemente para apoyar la instalaci\u00f3n de bater\u00edas de respaldo en instalaciones cr\u00edticas y en los hogares de clientes vulnerables en toda nuestra \u00e1rea de servicio. Estos recursos ayudar\u00e1n a reducir las facturas de electricidad y a aumentar la resistencia energ\u00e9tica y el uso de energ\u00edas limpias en nuestra \u00e1rea de servicio. Est\u00e9 atento a m\u00e1s actualizaciones sobre microrredes y m\u00e1s contenido en nuestro <a href=\"https:\/\/mcecleanenergy.org\/es\/category\/energy-expert\/\">Serie Experto en Energ\u00eda<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>MCE\u2019s Energy Expert Series takes a deeper dive into more complex energy topics like the development of the duck curve and the nuts and bolts of Net Energy Metering. Go [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":40083,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_searchwp_excluded":"","footnotes":""},"categories":[824],"tags":[356,531],"class_list":["post-40082","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-clean-energy","tag-energy-expert","tag-resiliency"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Energy Expert: Microgrids - MCE Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mcecleanenergy.org\/es\/energy-expert-microgrids\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Energy Expert: Microgrids\" \/>\n<meta property=\"og:description\" content=\"MCE\u2019s Energy Expert Series takes a deeper dive into more complex energy topics like the development of the duck curve and the nuts and bolts of Net Energy\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mcecleanenergy.org\/es\/energy-expert-microgrids\/\" \/>\n<meta property=\"og:site_name\" content=\"MCE \u2013 Community Choice Energy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mceCleanEnergy\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-16T16:57:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-01T22:56:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/microgrids-energy-expert-3-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rohan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MCECleanEnergy\" \/>\n<meta name=\"twitter:site\" content=\"@MCECleanEnergy\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rohan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/energy-expert-microgrids\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/energy-expert-microgrids\\\/\"},\"author\":{\"name\":\"Rohan\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#\\\/schema\\\/person\\\/8ce2f62799413aaa2b6868dc9b471748\"},\"headline\":\"Energy Expert: Microgrids\",\"datePublished\":\"2021-03-16T16:57:57+00:00\",\"dateModified\":\"2024-06-01T22:56:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/energy-expert-microgrids\\\/\"},\"wordCount\":997,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/energy-expert-microgrids\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/microgrids-energy-expert-3-1.jpg\",\"keywords\":[\"Energy Expert\",\"Resiliency\"],\"articleSection\":[\"Clean Energy\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mcecleanenergy.org\\\/energy-expert-microgrids\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/energy-expert-microgrids\\\/\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/energy-expert-microgrids\\\/\",\"name\":\"Energy Expert: Microgrids - MCE Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/energy-expert-microgrids\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/energy-expert-microgrids\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/microgrids-energy-expert-3-1.jpg\",\"datePublished\":\"2021-03-16T16:57:57+00:00\",\"dateModified\":\"2024-06-01T22:56:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/energy-expert-microgrids\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mcecleanenergy.org\\\/energy-expert-microgrids\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/energy-expert-microgrids\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/microgrids-energy-expert-3-1.jpg\",\"contentUrl\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/microgrids-energy-expert-3-1.jpg\",\"width\":1100,\"height\":440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/energy-expert-microgrids\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mcecleanenergy.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Energy Expert: Microgrids\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#website\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/\",\"name\":\"MCE \u2013 Community Choice Energy\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mcecleanenergy.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#organization\",\"name\":\"MCE\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/MCE_Logo_Full-Color_RGB_050324.png\",\"contentUrl\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/MCE_Logo_Full-Color_RGB_050324.png\",\"width\":5001,\"height\":2986,\"caption\":\"MCE\"},\"image\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mceCleanEnergy\\\/\",\"https:\\\/\\\/x.com\\\/MCECleanEnergy\",\"https:\\\/\\\/www.instagram.com\\\/mcecleanenergy\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mcecleanenergy\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/Mcecleanenergy\\\/\",\"https:\\\/\\\/en.wikipedia.org\\\/wiki\\\/Community_Choice_Aggregation#Marin_Clean_Energy\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#\\\/schema\\\/person\\\/8ce2f62799413aaa2b6868dc9b471748\",\"name\":\"Rohan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/08c0249ed3a34e3695a3cb94fc48aa840d636d2ba6af19ac1dd65e5303c3c992?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/08c0249ed3a34e3695a3cb94fc48aa840d636d2ba6af19ac1dd65e5303c3c992?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/08c0249ed3a34e3695a3cb94fc48aa840d636d2ba6af19ac1dd65e5303c3c992?s=96&d=mm&r=g\",\"caption\":\"Rohan\"},\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/es\\\/author\\\/rohan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Experto en energ\u00eda: Microredes - Blog de MCE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mcecleanenergy.org\/es\/energy-expert-microgrids\/","og_locale":"es_MX","og_type":"article","og_title":"Energy Expert: Microgrids","og_description":"MCE\u2019s Energy Expert Series takes a deeper dive into more complex energy topics like the development of the duck curve and the nuts and bolts of Net Energy","og_url":"https:\/\/mcecleanenergy.org\/es\/energy-expert-microgrids\/","og_site_name":"MCE \u2013 Community Choice Energy","article_publisher":"https:\/\/www.facebook.com\/mceCleanEnergy\/","article_published_time":"2021-03-16T16:57:57+00:00","article_modified_time":"2024-06-01T22:56:45+00:00","og_image":[{"width":1100,"height":440,"url":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/microgrids-energy-expert-3-1.jpg","type":"image\/jpeg"}],"author":"Rohan","twitter_card":"summary_large_image","twitter_creator":"@MCECleanEnergy","twitter_site":"@MCECleanEnergy","twitter_misc":{"Escrito por":"Rohan","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mcecleanenergy.org\/energy-expert-microgrids\/#article","isPartOf":{"@id":"https:\/\/mcecleanenergy.org\/energy-expert-microgrids\/"},"author":{"name":"Rohan","@id":"https:\/\/mcecleanenergy.org\/#\/schema\/person\/8ce2f62799413aaa2b6868dc9b471748"},"headline":"Energy Expert: Microgrids","datePublished":"2021-03-16T16:57:57+00:00","dateModified":"2024-06-01T22:56:45+00:00","mainEntityOfPage":{"@id":"https:\/\/mcecleanenergy.org\/energy-expert-microgrids\/"},"wordCount":997,"commentCount":0,"publisher":{"@id":"https:\/\/mcecleanenergy.org\/#organization"},"image":{"@id":"https:\/\/mcecleanenergy.org\/energy-expert-microgrids\/#primaryimage"},"thumbnailUrl":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/microgrids-energy-expert-3-1.jpg","keywords":["Energy Expert","Resiliency"],"articleSection":["Clean Energy"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mcecleanenergy.org\/energy-expert-microgrids\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mcecleanenergy.org\/energy-expert-microgrids\/","url":"https:\/\/mcecleanenergy.org\/energy-expert-microgrids\/","name":"Experto en energ\u00eda: Microredes - Blog de MCE","isPartOf":{"@id":"https:\/\/mcecleanenergy.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mcecleanenergy.org\/energy-expert-microgrids\/#primaryimage"},"image":{"@id":"https:\/\/mcecleanenergy.org\/energy-expert-microgrids\/#primaryimage"},"thumbnailUrl":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/microgrids-energy-expert-3-1.jpg","datePublished":"2021-03-16T16:57:57+00:00","dateModified":"2024-06-01T22:56:45+00:00","breadcrumb":{"@id":"https:\/\/mcecleanenergy.org\/energy-expert-microgrids\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mcecleanenergy.org\/energy-expert-microgrids\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mcecleanenergy.org\/energy-expert-microgrids\/#primaryimage","url":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/microgrids-energy-expert-3-1.jpg","contentUrl":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/microgrids-energy-expert-3-1.jpg","width":1100,"height":440},{"@type":"BreadcrumbList","@id":"https:\/\/mcecleanenergy.org\/energy-expert-microgrids\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mcecleanenergy.org\/"},{"@type":"ListItem","position":2,"name":"Energy Expert: Microgrids"}]},{"@type":"WebSite","@id":"https:\/\/mcecleanenergy.org\/#website","url":"https:\/\/mcecleanenergy.org\/","name":"MCE - Elecci\u00f3n comunitaria de la energ\u00eda","description":"","publisher":{"@id":"https:\/\/mcecleanenergy.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mcecleanenergy.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/mcecleanenergy.org\/#organization","name":"MCE","url":"https:\/\/mcecleanenergy.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mcecleanenergy.org\/#\/schema\/logo\/image\/","url":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/MCE_Logo_Full-Color_RGB_050324.png","contentUrl":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/MCE_Logo_Full-Color_RGB_050324.png","width":5001,"height":2986,"caption":"MCE"},"image":{"@id":"https:\/\/mcecleanenergy.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mceCleanEnergy\/","https:\/\/x.com\/MCECleanEnergy","https:\/\/www.instagram.com\/mcecleanenergy\/","https:\/\/www.linkedin.com\/company\/mcecleanenergy\/","https:\/\/www.youtube.com\/c\/Mcecleanenergy\/","https:\/\/en.wikipedia.org\/wiki\/Community_Choice_Aggregation#Marin_Clean_Energy"]},{"@type":"Person","@id":"https:\/\/mcecleanenergy.org\/#\/schema\/person\/8ce2f62799413aaa2b6868dc9b471748","name":"Rohan","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/08c0249ed3a34e3695a3cb94fc48aa840d636d2ba6af19ac1dd65e5303c3c992?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/08c0249ed3a34e3695a3cb94fc48aa840d636d2ba6af19ac1dd65e5303c3c992?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/08c0249ed3a34e3695a3cb94fc48aa840d636d2ba6af19ac1dd65e5303c3c992?s=96&d=mm&r=g","caption":"Rohan"},"url":"https:\/\/mcecleanenergy.org\/es\/author\/rohan\/"}]}},"_links":{"self":[{"href":"https:\/\/mcecleanenergy.org\/es\/wp-json\/wp\/v2\/posts\/40082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mcecleanenergy.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mcecleanenergy.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mcecleanenergy.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mcecleanenergy.org\/es\/wp-json\/wp\/v2\/comments?post=40082"}],"version-history":[{"count":0,"href":"https:\/\/mcecleanenergy.org\/es\/wp-json\/wp\/v2\/posts\/40082\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mcecleanenergy.org\/es\/wp-json\/wp\/v2\/media\/40083"}],"wp:attachment":[{"href":"https:\/\/mcecleanenergy.org\/es\/wp-json\/wp\/v2\/media?parent=40082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mcecleanenergy.org\/es\/wp-json\/wp\/v2\/categories?post=40082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mcecleanenergy.org\/es\/wp-json\/wp\/v2\/tags?post=40082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}