{"id":40204,"date":"2021-09-21T09:58:35","date_gmt":"2021-09-21T16:58:35","guid":{"rendered":"https:\/\/mcecleanenergy.org\/energy-101-electric-vehicles\/"},"modified":"2024-06-12T05:28:06","modified_gmt":"2024-06-12T12:28:06","slug":"energy-101-electric-vehicles","status":"publish","type":"post","link":"https:\/\/mcecleanenergy.org\/fr\/energy-101-electric-vehicles\/","title":{"rendered":"\u00c9nergie 101 : V\u00e9hicules \u00e9lectriques"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"40204\" class=\"elementor elementor-40204\" data-elementor-post-type=\"post\">\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-4ea4e554 e-flex e-con-boxed e-con e-parent\" data-id=\"4ea4e554\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9d936aa elementor-widget elementor-widget-text-editor\" data-id=\"9d936aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5><strong>La s\u00e9rie Energy 101 de MCE se concentre sur le pourquoi et le comment des \u00e9nergies renouvelables afin que vous puissiez en apprendre davantage sur des concepts tels que les avantages de la biomasse et la science derri\u00e8re l'\u00e9nergie solaire. Vous voulez en savoir plus ? Consultez les liens de ce blog pour en savoir plus sur <\/strong><strong>\u00c9nergie 101<\/strong><strong> ou pour plonger plus profond\u00e9ment dans notre <\/strong><strong>Expert en \u00e9nergie<\/strong><strong> s\u00e9rie.<\/strong><\/h5><p>Un v\u00e9hicule \u00e9lectrique (VE) est un v\u00e9hicule qui peut \u00eatre branch\u00e9 et fonctionner enti\u00e8rement ou partiellement \u00e0 l'\u00e9lectricit\u00e9. Les VE ont un impact moindre sur l'environnement que les v\u00e9hicules \u00e0 essence et permettent aux conducteurs d'\u00e9conomiser de l'argent sur l'essence et l'entretien du v\u00e9hicule.<\/p><h2>Quels sont les types de VE ?<\/h2><p>Il existe trois principaux types de VE : les v\u00e9hicules \u00e9lectriques \u00e0 batterie, les v\u00e9hicules \u00e9lectriques hybrides rechargeables et les v\u00e9hicules hybrides \u00e0 gaz. Le terme VE d\u00e9signe le plus souvent le premier type (v\u00e9hicules \u00e9lectriques \u00e0 batterie).<\/p><p><strong>V\u00e9hicules \u00e9lectriques \u00e0 batterie<\/strong><\/p><p>Les v\u00e9hicules \u00e9lectriques \u00e0 batterie (BEV) fonctionnent uniquement gr\u00e2ce \u00e0 la charge de la batterie et ne produisent pas d'\u00e9missions \u00e0 l'\u00e9chappement. Le port de charge des BEV ressemble \u00e0 celui des v\u00e9hicules \u00e0 essence traditionnels. Cependant, la voiture est connect\u00e9e \u00e0 une source d'\u00e9nergie et charg\u00e9e avec de l'\u00e9lectricit\u00e9 provenant du r\u00e9seau.<\/p><p><strong>V\u00e9hicules \u00e9lectriques hybrides rechargeables<\/strong><\/p><p>Les v\u00e9hicules \u00e9lectriques hybrides rechargeables (PHEV) fonctionnent \u00e0 l'\u00e9lectricit\u00e9 et utilisent le gaz comme carburant d'appoint. Ces v\u00e9hicules peuvent \u00eatre recharg\u00e9s \u00e0 une station de recharge VE normale et peuvent \u00e9galement \u00eatre remplis d'essence. Lorsque la batterie est \u00e9puis\u00e9e, les v\u00e9hicules hybrides rechargeables passent automatiquement au moteur \u00e0 combustion et produisent des \u00e9missions de gaz d'\u00e9chappement.<\/p><p><strong>V\u00e9hicules hybrides \u00e0 gaz<\/strong><\/p><p>Les v\u00e9hicules hybrides \u00e0 gaz (hybrides) ont des composants \u00e9lectriques pour r\u00e9duire la consommation d'essence, mais fonctionnent uniquement \u00e0 l'essence. Les voitures hybrides sont \u00e9quip\u00e9es d'un moteur \u00e0 combustion interne et d'un moteur \u00e9lectrique. Le moteur \u00e9lectrique fonctionne sur des batteries qui sont charg\u00e9es par le moteur et le freinage par r\u00e9cup\u00e9ration. L'assistance du moteur \u00e9lectrique offre les m\u00eames performances au v\u00e9hicule tout en consommant moins de carburant.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-71b94da2 e-flex e-con-boxed e-con e-parent\" data-id=\"71b94da2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-7605e4b4 e-con-full e-flex e-con e-child\" data-id=\"7605e4b4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-72dfe3d3 e-con-full e-flex e-con e-child\" data-id=\"72dfe3d3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d4190cb elementor-widget elementor-widget-heading\" data-id=\"d4190cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Comment recharger les VE ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c5e2c84 elementor-widget elementor-widget-text-editor\" data-id=\"5c5e2c84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Contrairement aux v\u00e9hicules \u00e0 essence qui n\u00e9cessitent une visite \u00e0 la station-service, les VE peuvent \u00eatre ravitaill\u00e9s partout o\u00f9 il y a de l'\u00e9lectricit\u00e9.<\/p><p><strong>Chargement \u00e0 domicile<\/strong><\/p><p>Vous pouvez recharger les VE \u00e0 la maison avec une prise de courant ordinaire de 120 volts. Cette recharge de niveau 1 permet g\u00e9n\u00e9ralement de recharger votre VE pendant la nuit pour un trajet moyen dans la r\u00e9gion de la Baie. Vous pouvez \u00e9galement passer \u00e0 une prise de 240 volts pour une charge de niveau 2, qui prend environ la moiti\u00e9 du temps de la charge de niveau 1.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-522592a8 e-con-full e-flex e-con e-child\" data-id=\"522592a8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2f4d158 elementor-widget elementor-widget-image\" data-id=\"2f4d158\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1324\" height=\"731\" src=\"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2020\/03\/EV-chargers-types-home-charging-1.jpg\" class=\"attachment-full size-full wp-image-3557\" alt=\"\" srcset=\"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2020\/03\/EV-chargers-types-home-charging-1.jpg 1324w, https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2020\/03\/EV-chargers-types-home-charging-1-300x166.jpg 300w, https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2020\/03\/EV-chargers-types-home-charging-1-1024x565.jpg 1024w, https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2020\/03\/EV-chargers-types-home-charging-1-768x424.jpg 768w\" sizes=\"(max-width: 1324px) 100vw, 1324px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-4f5a9eb e-flex e-con-boxed e-con e-parent\" data-id=\"4f5a9eb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c17f78c elementor-widget elementor-widget-text-editor\" data-id=\"c17f78c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Recharger loin de chez soi<\/strong><\/p><p>Les bornes de recharge pour VE se trouvent dans les parkings des \u00e9piceries ou des centres commerciaux, dans les garages, sur les lieux de travail, sur les aires de repos des autoroutes, dans les parcs publics, etc. Certains sites disposent m\u00eame de chargeurs rapides permettant de recharger votre voiture en 30 minutes seulement. MCE offre actuellement une recharge gratuite pour les VE \u00e0 notre bureau de San Rafael. T\u00e9l\u00e9chargez l'application Greenlots et cr\u00e9ez un compte pour recharger chez MCE. Pour trouver une borne de recharge pour VE pr\u00e8s de chez vous, visitez le site <a href=\"https:\/\/mcecleanenergy.org\/fr\/ev-drivers\/#EVChargingRates\">Carte PlugShare<\/a> sur le site web de MCE ou utilisez l'application ou la carte de localisation des bornes de recharge pour VE de votre choix.<\/p><h2>Les VE sont-ils plus propres que les v\u00e9hicules \u00e0 essence ?<\/h2><p>Les VE fonctionnent \u00e0 l'\u00e9lectricit\u00e9 plut\u00f4t qu'au diesel ou au gaz et produisent moins d'\u00e9missions qu'une voiture \u00e0 essence, voire pas d'\u00e9missions du tout. Les \u00e9missions totales produites par les VE d\u00e9pendent de l'approvisionnement local en \u00e9lectricit\u00e9. Cependant, les VE sont une option plus propre que les v\u00e9hicules \u00e0 essence dans les cas suivants <a href=\"https:\/\/www.ucsusa.org\/sites\/default\/files\/2020-05\/evs-cleaner-than-gasoline.pdf\" target=\"_blank\" rel=\"noopener\">toutes les r\u00e9gions<\/a> des \u00c9tats-Unis, quelle que soit la panne de courant, parce qu'ils sont extr\u00eamement \u00e9conomes en carburant. Alors que les v\u00e9hicules \u00e0 essence ne consomment que <a href=\"https:\/\/www.energy.gov\/articles\/top-10-things-you-didn-t-know-about-electric-vehicles\" target=\"_blank\" rel=\"noopener\">14-26%<\/a> de l'\u00e9nergie de l'essence, les VE peuvent utiliser jusqu'\u00e0 80% de l'\u00e9nergie de leur batterie. Les VE deviendront de plus en plus propres chaque ann\u00e9e \u00e0 mesure que les \u00c9tats-Unis introduiront davantage d'\u00e9nergie renouvelable sur le r\u00e9seau. Les habitants de la zone de service de MCE peuvent alimenter leurs VE avec 100% d'\u00e9nergie renouvelable lorsqu'ils optent pour le service de recharge de MCE. <a href=\"https:\/\/mcecleanenergy.org\/fr\/opt-up\/\">Deep Green<\/a> service \u00e9nerg\u00e9tique.<\/p><h2>Peut-on \u00e9lectrifier d'autres v\u00e9hicules ?<\/h2><p>Les v\u00e9hicules utilitaires moyens et lourds, tels que les autobus, les camions, les fourgonnettes et les tracteurs, sont responsables d'environ <a href=\"https:\/\/www.c2es.org\/content\/regulating-transportation-sector-carbon-emissions\/\" target=\"_blank\" rel=\"noopener\">24%<\/a> des \u00e9missions li\u00e9es au transport aux \u00c9tats-Unis. L'\u00e9lectrification de ces v\u00e9hicules commerciaux est une \u00e9tape essentielle pour atteindre les objectifs de z\u00e9ro \u00e9mission. Outre la r\u00e9duction des \u00e9missions, les v\u00e9hicules commerciaux \u00e9lectriques n\u00e9cessitent moins d'entretien et sont plus silencieux que les v\u00e9hicules commerciaux conventionnels. Des incitations accrues, des progr\u00e8s dans la technologie des batteries et des infrastructures de recharge plus d\u00e9velopp\u00e9es acc\u00e9l\u00e9reront l'\u00e9lectrification des v\u00e9hicules utilitaires moyens et lourds.<\/p><h2>Comment le MCE soutient-il l'adoption des v\u00e9hicules \u00e9lectriques ?<\/h2><p>MCE s'efforce d'accro\u00eetre l'adoption des v\u00e9hicules \u00e9lectriques par le biais de mesures incitatives en faveur des VE et de la recharge des VE. MCE propose une offre de $3,500 <a href=\"https:\/\/mcecleanenergy.org\/fr\/ev-drivers\/\">rabais<\/a> pour les clients qui remplissent les conditions requises pour l'achat ou la location de nouveaux VE. MCE peut \u00e9galement aider les clients \u00e9ligibles \u00e0 combiner la remise avec des incitations f\u00e9d\u00e9rales, nationales et locales. L'offre de MCE <a href=\"https:\/\/mcecleanenergy.org\/fr\/ev-charging\/\">Remise sur la recharge des VE<\/a> couvre \u00e0 la fois les grands et les petits projets de recharge (2-20+ ports). Le programme permet aux immeubles multifamiliaux et aux lieux de travail au prix du march\u00e9 et \u00e0 des prix abordables d'\u00e9conomiser jusqu'\u00e0 $3 000 par port. Si les propri\u00e9t\u00e9s optent pour Deep Green 100% d'\u00e9nergie renouvelable, elles peuvent obtenir $500 de plus par port de charge. MCE fournit \u00e9galement une assistance technique pendant les processus d'application et d'installation.<\/p><p><strong>Faits amusants<\/strong><\/p><ul><li>La premi\u00e8re voiture \u00e9lectrique a \u00e9t\u00e9 cr\u00e9\u00e9e en <a href=\"https:\/\/www.energy.gov\/timeline\/timeline-history-electric-car\" target=\"_blank\" rel=\"noopener\">1832<\/a>.<\/li><li>La Californie a le <a href=\"https:\/\/evadoption.com\/ev-charging-stations-statistics\/charging-stations-by-state\/\" target=\"_blank\" rel=\"noopener\">le plus grand nombre de chargeurs de VE<\/a> de tous les \u00c9tats des \u00c9tats-Unis.<\/li><li>Le nombre de VE a augment\u00e9 de <a href=\"https:\/\/www.iea.org\/reports\/global-ev-outlook-2020\" target=\"_blank\" rel=\"noopener\">40%<\/a> \u00e0 l'\u00e9chelle mondiale entre 2019 et 2020.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>MCE\u2019s Energy 101 Series focuses on the why and how of renewable energy so that you can learn more about concepts like the benefits of biomass and the science behind [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":40205,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_theme","format":"standard","meta":{"_acf_changed":false,"_searchwp_excluded":"","footnotes":""},"categories":[824,825],"tags":[410],"class_list":["post-40204","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-clean-energy","category-clean-transportation","tag-ev-charging"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Energy 101: Electric Vehicles - MCE Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mcecleanenergy.org\/fr\/energy-101-electric-vehicles\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Energy 101: Electric Vehicles\" \/>\n<meta property=\"og:description\" content=\"MCE\u2019s Energy 101 Series focuses on the why and how of renewable energy so that you can learn more about concepts like the benefits of biomass and the\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mcecleanenergy.org\/fr\/energy-101-electric-vehicles\/\" \/>\n<meta property=\"og:site_name\" content=\"MCE \u2013 Community Choice Energy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mceCleanEnergy\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-21T16:58:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-12T12:28:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/energy-101-evs-min.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rohan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MCECleanEnergy\" \/>\n<meta name=\"twitter:site\" content=\"@MCECleanEnergy\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rohan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/energy-101-electric-vehicles\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/energy-101-electric-vehicles\\\/\"},\"author\":{\"name\":\"Rohan\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#\\\/schema\\\/person\\\/8ce2f62799413aaa2b6868dc9b471748\"},\"headline\":\"Energy 101: Electric Vehicles\",\"datePublished\":\"2021-09-21T16:58:35+00:00\",\"dateModified\":\"2024-06-12T12:28:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/energy-101-electric-vehicles\\\/\"},\"wordCount\":806,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/energy-101-electric-vehicles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/energy-101-evs-min.jpg\",\"keywords\":[\"ev charging\"],\"articleSection\":[\"Clean Energy\",\"Clean Transportation\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mcecleanenergy.org\\\/energy-101-electric-vehicles\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/energy-101-electric-vehicles\\\/\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/energy-101-electric-vehicles\\\/\",\"name\":\"Energy 101: Electric Vehicles - MCE Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/energy-101-electric-vehicles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/energy-101-electric-vehicles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/energy-101-evs-min.jpg\",\"datePublished\":\"2021-09-21T16:58:35+00:00\",\"dateModified\":\"2024-06-12T12:28:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/energy-101-electric-vehicles\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mcecleanenergy.org\\\/energy-101-electric-vehicles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/energy-101-electric-vehicles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/energy-101-evs-min.jpg\",\"contentUrl\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/energy-101-evs-min.jpg\",\"width\":1100,\"height\":440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/energy-101-electric-vehicles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mcecleanenergy.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Energy 101: Electric Vehicles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#website\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/\",\"name\":\"MCE \u2013 Community Choice Energy\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mcecleanenergy.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#organization\",\"name\":\"MCE\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/MCE_Logo_Full-Color_RGB_050324.png\",\"contentUrl\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/MCE_Logo_Full-Color_RGB_050324.png\",\"width\":5001,\"height\":2986,\"caption\":\"MCE\"},\"image\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mceCleanEnergy\\\/\",\"https:\\\/\\\/x.com\\\/MCECleanEnergy\",\"https:\\\/\\\/www.instagram.com\\\/mcecleanenergy\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mcecleanenergy\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/Mcecleanenergy\\\/\",\"https:\\\/\\\/en.wikipedia.org\\\/wiki\\\/Community_Choice_Aggregation#Marin_Clean_Energy\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#\\\/schema\\\/person\\\/8ce2f62799413aaa2b6868dc9b471748\",\"name\":\"Rohan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/08c0249ed3a34e3695a3cb94fc48aa840d636d2ba6af19ac1dd65e5303c3c992?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/08c0249ed3a34e3695a3cb94fc48aa840d636d2ba6af19ac1dd65e5303c3c992?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/08c0249ed3a34e3695a3cb94fc48aa840d636d2ba6af19ac1dd65e5303c3c992?s=96&d=mm&r=g\",\"caption\":\"Rohan\"},\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/fr\\\/author\\\/rohan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00c9nergie 101 : V\u00e9hicules \u00e9lectriques - Blog MCE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mcecleanenergy.org\/fr\/energy-101-electric-vehicles\/","og_locale":"fr_FR","og_type":"article","og_title":"Energy 101: Electric Vehicles","og_description":"MCE\u2019s Energy 101 Series focuses on the why and how of renewable energy so that you can learn more about concepts like the benefits of biomass and the","og_url":"https:\/\/mcecleanenergy.org\/fr\/energy-101-electric-vehicles\/","og_site_name":"MCE \u2013 Community Choice Energy","article_publisher":"https:\/\/www.facebook.com\/mceCleanEnergy\/","article_published_time":"2021-09-21T16:58:35+00:00","article_modified_time":"2024-06-12T12:28:06+00:00","og_image":[{"width":1100,"height":440,"url":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/energy-101-evs-min.jpg","type":"image\/jpeg"}],"author":"Rohan","twitter_card":"summary_large_image","twitter_creator":"@MCECleanEnergy","twitter_site":"@MCECleanEnergy","twitter_misc":{"\u00c9crit par":"Rohan","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mcecleanenergy.org\/energy-101-electric-vehicles\/#article","isPartOf":{"@id":"https:\/\/mcecleanenergy.org\/energy-101-electric-vehicles\/"},"author":{"name":"Rohan","@id":"https:\/\/mcecleanenergy.org\/#\/schema\/person\/8ce2f62799413aaa2b6868dc9b471748"},"headline":"Energy 101: Electric Vehicles","datePublished":"2021-09-21T16:58:35+00:00","dateModified":"2024-06-12T12:28:06+00:00","mainEntityOfPage":{"@id":"https:\/\/mcecleanenergy.org\/energy-101-electric-vehicles\/"},"wordCount":806,"commentCount":0,"publisher":{"@id":"https:\/\/mcecleanenergy.org\/#organization"},"image":{"@id":"https:\/\/mcecleanenergy.org\/energy-101-electric-vehicles\/#primaryimage"},"thumbnailUrl":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/energy-101-evs-min.jpg","keywords":["ev charging"],"articleSection":["Clean Energy","Clean Transportation"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mcecleanenergy.org\/energy-101-electric-vehicles\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mcecleanenergy.org\/energy-101-electric-vehicles\/","url":"https:\/\/mcecleanenergy.org\/energy-101-electric-vehicles\/","name":"\u00c9nergie 101 : V\u00e9hicules \u00e9lectriques - Blog MCE","isPartOf":{"@id":"https:\/\/mcecleanenergy.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mcecleanenergy.org\/energy-101-electric-vehicles\/#primaryimage"},"image":{"@id":"https:\/\/mcecleanenergy.org\/energy-101-electric-vehicles\/#primaryimage"},"thumbnailUrl":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/energy-101-evs-min.jpg","datePublished":"2021-09-21T16:58:35+00:00","dateModified":"2024-06-12T12:28:06+00:00","breadcrumb":{"@id":"https:\/\/mcecleanenergy.org\/energy-101-electric-vehicles\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mcecleanenergy.org\/energy-101-electric-vehicles\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mcecleanenergy.org\/energy-101-electric-vehicles\/#primaryimage","url":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/energy-101-evs-min.jpg","contentUrl":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/energy-101-evs-min.jpg","width":1100,"height":440},{"@type":"BreadcrumbList","@id":"https:\/\/mcecleanenergy.org\/energy-101-electric-vehicles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mcecleanenergy.org\/"},{"@type":"ListItem","position":2,"name":"Energy 101: Electric Vehicles"}]},{"@type":"WebSite","@id":"https:\/\/mcecleanenergy.org\/#website","url":"https:\/\/mcecleanenergy.org\/","name":"MCE - \u00c9nergie de choix communautaire","description":"","publisher":{"@id":"https:\/\/mcecleanenergy.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mcecleanenergy.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mcecleanenergy.org\/#organization","name":"MCE","url":"https:\/\/mcecleanenergy.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mcecleanenergy.org\/#\/schema\/logo\/image\/","url":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/MCE_Logo_Full-Color_RGB_050324.png","contentUrl":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/MCE_Logo_Full-Color_RGB_050324.png","width":5001,"height":2986,"caption":"MCE"},"image":{"@id":"https:\/\/mcecleanenergy.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mceCleanEnergy\/","https:\/\/x.com\/MCECleanEnergy","https:\/\/www.instagram.com\/mcecleanenergy\/","https:\/\/www.linkedin.com\/company\/mcecleanenergy\/","https:\/\/www.youtube.com\/c\/Mcecleanenergy\/","https:\/\/en.wikipedia.org\/wiki\/Community_Choice_Aggregation#Marin_Clean_Energy"]},{"@type":"Person","@id":"https:\/\/mcecleanenergy.org\/#\/schema\/person\/8ce2f62799413aaa2b6868dc9b471748","name":"Rohan","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/08c0249ed3a34e3695a3cb94fc48aa840d636d2ba6af19ac1dd65e5303c3c992?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/08c0249ed3a34e3695a3cb94fc48aa840d636d2ba6af19ac1dd65e5303c3c992?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/08c0249ed3a34e3695a3cb94fc48aa840d636d2ba6af19ac1dd65e5303c3c992?s=96&d=mm&r=g","caption":"Rohan"},"url":"https:\/\/mcecleanenergy.org\/fr\/author\/rohan\/"}]}},"_links":{"self":[{"href":"https:\/\/mcecleanenergy.org\/fr\/wp-json\/wp\/v2\/posts\/40204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mcecleanenergy.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mcecleanenergy.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mcecleanenergy.org\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mcecleanenergy.org\/fr\/wp-json\/wp\/v2\/comments?post=40204"}],"version-history":[{"count":0,"href":"https:\/\/mcecleanenergy.org\/fr\/wp-json\/wp\/v2\/posts\/40204\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mcecleanenergy.org\/fr\/wp-json\/wp\/v2\/media\/40205"}],"wp:attachment":[{"href":"https:\/\/mcecleanenergy.org\/fr\/wp-json\/wp\/v2\/media?parent=40204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mcecleanenergy.org\/fr\/wp-json\/wp\/v2\/categories?post=40204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mcecleanenergy.org\/fr\/wp-json\/wp\/v2\/tags?post=40204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}