{"id":82734,"date":"2026-05-07T09:00:00","date_gmt":"2026-05-07T16:00:00","guid":{"rendered":"https:\/\/mcecleanenergy.org\/?p=82734"},"modified":"2026-05-07T09:24:38","modified_gmt":"2026-05-07T16:24:38","slug":"young-leaders-in-action-mce-recognizes-young-bay-area-changemakers","status":"publish","type":"post","link":"https:\/\/mcecleanenergy.org\/fr\/young-leaders-in-action-mce-recognizes-young-bay-area-changemakers\/","title":{"rendered":"Jeunes Leaders en Action : MCE r\u00e9compense les jeunes artisans du changement dans la baie de San Francisco"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"82734\" class=\"elementor elementor-82734\" data-elementor-post-type=\"post\">\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-c064980 e-flex e-con-boxed e-con e-parent\" data-id=\"c064980\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1b44975 elementor-widget elementor-widget-text-editor\" data-id=\"1b44975\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le 25 avril 2026, MCE a honor\u00e9 huit laur\u00e9ats de son inaugural <b>Gr\u00e2ce au Youth Impact Award<\/b>. Ce prix r\u00e9compense de jeunes gens exceptionnels dans la zone de service de MCE qui font une diff\u00e9rence significative par leur action et leur leadership environnementaux dans leurs communaut\u00e9s.<\/p><p>Les laur\u00e9ats de cette ann\u00e9e sont les suivants<span class=\"Apple-converted-space\">\u00a0<\/span><\/p><ul><li>Erik Hagstrom et Syrus Tator, comt\u00e9 de Solano<\/li><li>Claire Mulligan et Gemma Roberts, comt\u00e9 de Napa<span class=\"Apple-converted-space\">\u00a0<\/span><\/li><li>Azucena Macias et Raini Chugh, Comt\u00e9 de Contra Costa<span class=\"Apple-converted-space\">\u00a0<\/span><\/li><li>Alex Macias et Ben Smulewitz, comt\u00e9 de Marin<span class=\"Apple-converted-space\">\u00a0<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba37059 elementor-widget elementor-widget-spacer\" data-id=\"ba37059\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-f75b5eb e-flex e-con-boxed e-con e-parent\" data-id=\"f75b5eb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d8e6b8 elementor-widget elementor-widget-text-editor\" data-id=\"1d8e6b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Erik Hagstrom<span class=\"Apple-converted-space\">\u00a0<\/span><\/b><\/p><p>Erik a \u00e9t\u00e9 inspir\u00e9 dans son enfance \u00e0 s'int\u00e9resser \u00e0 la gestion de l'environnement apr\u00e8s avoir vu les espaces naturels de la r\u00e9gion de la Baie \u00eatre affect\u00e9s par l'expansion urbaine. Il a rapidement reconnu le pouvoir d'une personne mobilisant les autres, et il consid\u00e8re son travail environnemental comme une forme de service envers les communaut\u00e9s du monde entier.<\/p><p>Il comprend que l'\u00e9chec est une opportunit\u00e9 de croissance, et il accepte la mani\u00e8re dont l'action collective et le travail d'\u00e9quipe peuvent transformer les revers en le\u00e7ons partag\u00e9es, accumulant ainsi des connaissances et am\u00e9liorant les r\u00e9sultats pour toutes les personnes concern\u00e9es. Ses efforts ont permis de financer et de loger des jeunes plac\u00e9s en famille d'accueil, le <b>la r\u00e9cup\u00e9ration de 1,6 million de kilos de denr\u00e9es alimentaires, ainsi que l&#x27;adoption d&#x27;un r\u00e8glement d&#x27;urbanisme in\u00e9dit qui permettra d&#x27;apporter 1 200 000 dollars aux communaut\u00e9s locales du comt\u00e9 de Solano<\/b>.<\/p><p>Si vous souhaitez vous impliquer dans l'action climatique, Erik recommande : \u201c Trouvez d'autres personnes qui se soucient de choses similaires et travaillez-y ensemble. Rien qu'en trouvant une autre personne pour travailler sur quelque chose ensemble, vous serez plus engag\u00e9 \u00e0 mener le projet \u00e0 terme, le r\u00e9sultat sera meilleur gr\u00e2ce \u00e0 deux esprits travaillant ensemble, et vous attirerez davantage l'attention (surtout si vous donnez un nom \u00e0 votre duo). \u201d<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74296db elementor-widget elementor-widget-text-editor\" data-id=\"74296db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Syrus Tator<\/b><\/p><p>La m\u00e8re de Syrus lui a appris \u00e0 avoir conscience de l'environnement d\u00e8s son plus jeune \u00e2ge. Pendant des ann\u00e9es, elle a collect\u00e9 et conserv\u00e9 des produits frais issus de fermes et de march\u00e9s qui, autrement, auraient \u00e9t\u00e9 gaspill\u00e9s. Elle est intervenue pour relancer l'initiative Solano Gleaning apr\u00e8s qu'elle ait perdu de son \u00e9lan, endossant le r\u00f4le de sa nouvelle fondatrice et se concentrant sur la r\u00e9duction du gaspillage alimentaire tout en am\u00e9liorant l'acc\u00e8s \u00e0 la nourriture \u00e0 Vallejo.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p><p>Gr\u00e2ce \u00e0 des partenariats tels que sa collaboration avec Food is Free Bay Area, elle est <b>aid\u00e9 \u00e0 r\u00e9cup\u00e9rer et redistribuer des milliers de livres de produits frais aux r\u00e9sidents en situation d'ins\u00e9curit\u00e9 alimentaire.<\/b> Ces efforts d\u00e9tournent les d\u00e9chets des d\u00e9charges, r\u00e9duisent les \u00e9missions de m\u00e9thane et soutiennent un syst\u00e8me alimentaire plus durable et centr\u00e9 sur la communaut\u00e9. Elle a continu\u00e9 \u00e0 faire progresser ce travail avec le soutien de son \u00e9quipe d\u00e9vou\u00e9e qui la maintient motiv\u00e9e face aux d\u00e9fis.<\/p><p>Elle attribue \u00e9galement une grande partie de sa force et de sa pers\u00e9v\u00e9rance \u00e0 l'\u00e9quipe incroyable qui l'entoure. Lorsque le travail devient difficile, c'est leur d\u00e9vouement et leur soutien partag\u00e9s qui la maintiennent motiv\u00e9e \u00e0 continuer et \u00e0 avoir un impact.<\/p><p>\u201c La chose la plus importante quand on d\u00e9bute un projet, c'est de trouver une bonne \u00e9quipe avec qui le r\u00e9aliser \u201d, a dit Syrus.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d3501da elementor-widget elementor-widget-text-editor\" data-id=\"d3501da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Claire Mulligan et Gemma Roberts<span class=\"Apple-converted-space\">\u00a0<\/span><\/b><\/p><p>Claire et Gemma sont stagiaires au Sierra Club de Napa, dont les voix et le leadership ont eu un impact consid\u00e9rable sur plusieurs projets environnementaux. Le conseil municipal d'American Canyon a vot\u00e9 pour ajouter des protections environnementales aux zones humides voisines lorsque Claire et Gemma ont fait des commentaires publics les exhortant \u00e0 le faire. Bien que ce duo dynamique soit copr\u00e9sident du club environnemental de leur \u00e9cole et collabore \u00e0 un podcast ax\u00e9 sur le climat, Eco-Unfiltered, elles sont individuellement engag\u00e9es dans l'action climatique \u00e0 Napa.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p><p>Claire a commenc\u00e9 son militantisme climatique au coll\u00e8ge apr\u00e8s les incendies de for\u00eat de Napa en 2017. Ces incendies ont ouvert ses yeux aux cons\u00e9quences locales du changement climatique. Dans son lyc\u00e9e, Claire a dirig\u00e9 un <b>campagne de sensibilisation \u00e9tudiante pour prot\u00e9ger un ruisseau local de la contamination \u2014 un effort qui a contribu\u00e9 \u00e0 soutenir le retour du saumon et de l'acieride dans la r\u00e9gion de Napa.<\/b><b><\/b><\/p><p>\u201c N'attendez pas le changement. Soyez le changement \u201d, d\u00e9clara Claire.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p><p>Gemma s'est lanc\u00e9e dans la d\u00e9fense du climat apr\u00e8s s'\u00eatre sentie impuissante face \u00e0 l'\u00e9tat du climat. Elle s'est impliqu\u00e9e aupr\u00e8s de diverses organisations d'action climatique, dont Napa Schools for Climate Action, ce qui a suscit\u00e9 une passion pour le militantisme environnemental. Gemma a produit une vid\u00e9o de sensibilisation publique pour le Sierra Club, soulignant l'importance de prot\u00e9ger les zones humides de la baie de San Francisco.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p><p>\u201cLa peur \u00e9crasante que j'ai ressentie dans ma jeunesse s'est transform\u00e9e en passion pour la d\u00e9fense des droits, et j'ai pu la canaliser dans un travail significatif qui contribuera \u00e0 un changement positif pour notre environnement commun\u201d, a d\u00e9clar\u00e9 Gemma.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e89cd22 elementor-widget elementor-widget-text-editor\" data-id=\"e89cd22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Azucena Macias<span class=\"Apple-converted-space\">\u00a0<\/span><\/b><\/p><p>Azucena a \u00e9t\u00e9 initi\u00e9e au travail environnemental d\u00e8s son plus jeune \u00e2ge gr\u00e2ce \u00e0 l'entreprise d'am\u00e9nagement paysager de sa famille. En tant qu'\u00e9tudiante en architecture paysag\u00e8re, ses connaissances des plantes et de l'am\u00e9nagement paysager ont \u00e9t\u00e9 d\u00e9terminantes en tant que b\u00e9n\u00e9vole pour The Watershed Project. Elle a <b>restaur\u00e9 deux cours d'eau pour r\u00e9duire les risques d'inondation \u00e0 Richmond, entretenu deux noues et jardins \u00e0 pollinisateurs, et install\u00e9 un syst\u00e8me de r\u00e9cup\u00e9ration d'eau de pluie et un jardin de pluie pour les r\u00e9sidents.<\/b> L'\u00e9ducation communautaire fait partie int\u00e9grante de son activisme. Elle a con\u00e7u un mod\u00e8le physique d\u00e9montrant les impacts de l'\u00e9l\u00e9vation du niveau de la mer sur les eaux souterraines, augmentant ainsi l'acc\u00e8s \u00e0 l'\u00e9ducation environnementale pour les jeunes et les communaut\u00e9s hispanophones.<span class=\"Apple-converted-space\">\u00a0 \u00a0<\/span><\/p><p>\u201c Ce n'est qu'en \u00e9tudiant l'architecture paysag\u00e8re et en travaillant dans la restauration que j'ai compris l'impact plus profond de notre environnement sur les gens \u201d, a d\u00e9clar\u00e9 Azucena. \u201c Cela m'a montr\u00e9 que ce travail ne concerne pas seulement les plantes ou le design, mais les gens, la culture et la cr\u00e9ation d'espaces qui soutiennent les communaut\u00e9s. \u201d<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04fb81d elementor-widget elementor-widget-text-editor\" data-id=\"04fb81d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Raini Chugh<\/b><\/p><p>Raini a commenc\u00e9 son parcours pour l'action climatique en troisi\u00e8me ann\u00e9e. Elle a ralli\u00e9 ses camarades de classe pour cr\u00e9er le \u00ab Project Earth Team \u00bb, un groupe de ses pairs qui a travaill\u00e9 \u00e0 la r\u00e9duction d'un probl\u00e8me qu'ils pouvaient constater dans leur \u00e9cole primaire, le ralenti des voitures. <b>Au cours des 7 derni\u00e8res ann\u00e9es, elle s'est engag\u00e9e aupr\u00e8s des dirigeants de la ville, a sensibilis\u00e9 le public et a fait progresser les politiques sans ralenti dans tout le comt\u00e9 de Contra Costa.<\/b> Ses efforts ont contribu\u00e9 \u00e0 des proclamations municipales, des campagnes \u00e9ducatives et des panneaux visibles dans les \u00e9coles et les espaces communautaires, entra\u00eenant des changements de comportement durables et r\u00e9duisant les \u00e9missions autour des \u00e9coles locales.<span class=\"Apple-converted-space\">\u00a0 <\/span>Son message met l'accent sur les voix des jeunes qui impulsent le changement local, \u00e0 commencer par les \u00e9coles. \u2018 Notre avenir, nos voix, notre pouvoir \u2019, nous nous attaquons \u00e0 la crise climatique en collaborant avec nos \u00e9coles et nos villes locales pour adopter des politiques environnementales plus strictes.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p><p>\u201c Face \u00e0 un probl\u00e8me aussi massif que la crise climatique, l'action collective est l'outil le plus puissant dont nous disposons. Si nous nous unissons dans nos communaut\u00e9s et poussons les d\u00e9cideurs locaux \u00e0 agir sur les questions climatiques, nous pouvons \u0153uvrer ensemble vers le m\u00eame objectif d'un avenir plus durable \u201d, a d\u00e9clar\u00e9 Raini.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-08a5270 elementor-widget elementor-widget-text-editor\" data-id=\"08a5270\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Alex Macias<span class=\"Apple-converted-space\">\u00a0<\/span><\/b><\/p><p>Alex attribue une le\u00e7on de quatri\u00e8me ann\u00e9e sur la mont\u00e9e du niveau de la mer \u00e0 son \u00e9veil environnemental et \u00e0 sa passion pour la pr\u00e9servation des terres et l'\u00e9ducation en plein air. Alex a particip\u00e9 \u00e0 des actions de service pratiques <b>des projets visant \u00e0 pr\u00e9server d'importantes r\u00e9serves naturelles telles que le lac Lagunitas et la r\u00e9serve Marin Audubon<\/b>. Comprenant le pouvoir personnel de l'\u00e9ducation au climat, Alex participe activement \u00e0 des programmes pour jeunes afin d'enseigner aux \u00e9l\u00e8ves du primaire et du coll\u00e8ge la gestion de l'environnement, le travail d'\u00e9quipe et le lien avec le monde naturel. Il a d\u00e9velopp\u00e9 des le\u00e7ons d'\u00e9ducation climatique pour le primaire afin d'expliquer des concepts complexes tels que l'\u00e9l\u00e9vation du niveau de la mer \u00e0 des \u00e9l\u00e8ves du primaire, donnant aux enfants les moyens de comprendre et de se soucier de l'avenir de leur communaut\u00e9.<\/p><p>\u201c Visitez vos parcs \u201d dit Alex. \u201c C\u2019est le moyen le plus simple de vous sentir connect\u00e9 \u00e0 votre environnement et de trouver des occasions de faire une diff\u00e9rence. \u201d<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-566fa97 elementor-widget elementor-widget-text-editor\" data-id=\"566fa97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Ben Smulewitz<\/b><\/p><p>Ben attribue \u00e0 sa formation au Marin School for Environmental Leadership un \u00e9lan \u00e0 sa conscience et \u00e0 son leadership environnementaux. Son approche de la d\u00e9fense de l'environnement est intersectionnelle et visionnaire. Ben est un b\u00e9n\u00e9vole principal pour le <b>Ceres Community Project, o\u00f9 il dispense des cours sur le d\u00e9veloppement durable tout en cuisinant plus de 1000 repas sains pour des clients atteints de maladies auto-immunes.<\/b> Lors de sa deuxi\u00e8me et troisi\u00e8me ann\u00e9e, il a fond\u00e9 une boutique de robes de bal dans son lyc\u00e9e, ainsi qu'une entreprise durable, Reclaimed Roots. Sa boutique de robes de bal s'est d\u00e9velopp\u00e9e pour inclure plus de 250 robes de soir\u00e9e et 15 costumes, sans frais pour les \u00e9l\u00e8ves, r\u00e9duisant ainsi les d\u00e9chets textiles en d\u00e9charge, tout en rendant le bal abordable pour les \u00e9l\u00e8ves. Son entreprise, Reclaimed Roots, utilise des bacs \u00e0 herbes pour d\u00e9tourner plus de 140 m\u00e8tres de bois de la d\u00e9charge, tout en r\u00e9duisant les \u00e9missions de CO2 et en sensibilisant la communaut\u00e9 au jardinage sans pesticides nocifs.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p><p>Ben a d\u00e9clar\u00e9 : \u201c M\u00eame si vous n'avez pas l'impression de faire une diff\u00e9rence, m\u00eame la plus petite action peut avoir un grand impact. \u201d<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-757fda7 e-flex e-con-boxed e-con e-parent\" data-id=\"757fda7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-64101ec elementor-widget elementor-widget-spacer\" data-id=\"64101ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>On April 25, 2026, MCE honored eight recipients of its inaugural Because of Youth Impact Award. This award recognizes outstanding young people across MCE\u2019s service area who are making a [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":82839,"comment_status":"closed","ping_status":"open","sticky":false,"template":"elementor_theme","format":"standard","meta":{"_acf_changed":false,"_searchwp_excluded":"","footnotes":""},"categories":[558,823],"tags":[392,95,174],"class_list":["post-82734","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-the-community","category-sustainability-and-climate-action","tag-bay-area","tag-renewable-energy","tag-sustainability"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Young Leaders in Action: MCE Recognizes Young Bay Area Changemakers - MCE Blog<\/title>\n<meta name=\"description\" content=\"MCE recently honored 8 recipients of its inaugural Because of Youth Impact Award recognizing outstanding young people in the area who are making a meaningful difference through environmental action and leadership in their communities.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mcecleanenergy.org\/fr\/young-leaders-in-action-mce-recognizes-young-bay-area-changemakers\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Young Leaders in Action: MCE Recognizes Young Bay Area Changemakers\" \/>\n<meta property=\"og:description\" content=\"On April 25, 2026, MCE honored eight recipients of its inaugural Because of Youth Impact Award. This award recognizes outstanding young people across\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mcecleanenergy.org\/fr\/young-leaders-in-action-mce-recognizes-young-bay-area-changemakers\/\" \/>\n<meta property=\"og:site_name\" content=\"MCE \u2013 Community Choice Energy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mceCleanEnergy\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-07T16:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-07T16:24:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2026\/05\/because-of-youth-2026-blog.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1180\" \/>\n\t<meta property=\"og:image:height\" content=\"475\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Debbie Lamb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MCECleanEnergy\" \/>\n<meta name=\"twitter:site\" content=\"@MCECleanEnergy\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Debbie Lamb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/young-leaders-in-action-mce-recognizes-young-bay-area-changemakers\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/young-leaders-in-action-mce-recognizes-young-bay-area-changemakers\\\/\"},\"author\":{\"name\":\"Debbie Lamb\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#\\\/schema\\\/person\\\/529ce2d4ac862fbb09c6c0a9b0b952cd\"},\"headline\":\"Young Leaders in Action: MCE Recognizes Young Bay Area Changemakers\",\"datePublished\":\"2026-05-07T16:00:00+00:00\",\"dateModified\":\"2026-05-07T16:24:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/young-leaders-in-action-mce-recognizes-young-bay-area-changemakers\\\/\"},\"wordCount\":1319,\"publisher\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/young-leaders-in-action-mce-recognizes-young-bay-area-changemakers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/because-of-youth-2026-blog.png\",\"keywords\":[\"Bay Area\",\"Renewable Energy\",\"Sustainability\"],\"articleSection\":[\"In the Community\",\"Sustainability and Climate Action\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/young-leaders-in-action-mce-recognizes-young-bay-area-changemakers\\\/\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/young-leaders-in-action-mce-recognizes-young-bay-area-changemakers\\\/\",\"name\":\"Young Leaders in Action: MCE Recognizes Young Bay Area Changemakers - MCE Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/young-leaders-in-action-mce-recognizes-young-bay-area-changemakers\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/young-leaders-in-action-mce-recognizes-young-bay-area-changemakers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/because-of-youth-2026-blog.png\",\"datePublished\":\"2026-05-07T16:00:00+00:00\",\"dateModified\":\"2026-05-07T16:24:38+00:00\",\"description\":\"MCE recently honored 8 recipients of its inaugural Because of Youth Impact Award recognizing outstanding young people in the area who are making a meaningful difference through environmental action and leadership in their communities.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/young-leaders-in-action-mce-recognizes-young-bay-area-changemakers\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mcecleanenergy.org\\\/young-leaders-in-action-mce-recognizes-young-bay-area-changemakers\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/young-leaders-in-action-mce-recognizes-young-bay-area-changemakers\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/because-of-youth-2026-blog.png\",\"contentUrl\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/because-of-youth-2026-blog.png\",\"width\":1180,\"height\":475,\"caption\":\"Because of Youth Award Recipients 2026\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/young-leaders-in-action-mce-recognizes-young-bay-area-changemakers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mcecleanenergy.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Young Leaders in Action: MCE Recognizes Young Bay Area Changemakers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#website\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/\",\"name\":\"MCE \u2013 Community Choice Energy\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mcecleanenergy.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#organization\",\"name\":\"MCE\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/MCE_Logo_Full-Color_RGB_050324.png\",\"contentUrl\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/MCE_Logo_Full-Color_RGB_050324.png\",\"width\":5001,\"height\":2986,\"caption\":\"MCE\"},\"image\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mceCleanEnergy\\\/\",\"https:\\\/\\\/x.com\\\/MCECleanEnergy\",\"https:\\\/\\\/www.instagram.com\\\/mcecleanenergy\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mcecleanenergy\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/Mcecleanenergy\\\/\",\"https:\\\/\\\/en.wikipedia.org\\\/wiki\\\/Community_Choice_Aggregation#Marin_Clean_Energy\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#\\\/schema\\\/person\\\/529ce2d4ac862fbb09c6c0a9b0b952cd\",\"name\":\"Debbie Lamb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c439b0a089c2fd256f9db2b902d716abcbed16d561521cc3bbf4dfa4a1cf2b5a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c439b0a089c2fd256f9db2b902d716abcbed16d561521cc3bbf4dfa4a1cf2b5a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c439b0a089c2fd256f9db2b902d716abcbed16d561521cc3bbf4dfa4a1cf2b5a?s=96&d=mm&r=g\",\"caption\":\"Debbie Lamb\"},\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/fr\\\/author\\\/debbie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Jeunes leaders en action : MCE r\u00e9compense les jeunes agents de changement de la Baie \u2013 Blog MCE","description":"MCE a r\u00e9cemment honor\u00e9 8 laur\u00e9ats de son premier prix d'impact \u00ab Gr\u00e2ce aux jeunes \u00bb reconnaissant de jeunes exceptionnels de la r\u00e9gion qui font une diff\u00e9rence significative par leur action environnementale et leur leadership dans leurs communaut\u00e9s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mcecleanenergy.org\/fr\/young-leaders-in-action-mce-recognizes-young-bay-area-changemakers\/","og_locale":"fr_FR","og_type":"article","og_title":"Young Leaders in Action: MCE Recognizes Young Bay Area Changemakers","og_description":"On April 25, 2026, MCE honored eight recipients of its inaugural Because of Youth Impact Award. This award recognizes outstanding young people across","og_url":"https:\/\/mcecleanenergy.org\/fr\/young-leaders-in-action-mce-recognizes-young-bay-area-changemakers\/","og_site_name":"MCE \u2013 Community Choice Energy","article_publisher":"https:\/\/www.facebook.com\/mceCleanEnergy\/","article_published_time":"2026-05-07T16:00:00+00:00","article_modified_time":"2026-05-07T16:24:38+00:00","og_image":[{"width":1180,"height":475,"url":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2026\/05\/because-of-youth-2026-blog.png","type":"image\/png"}],"author":"Debbie Lamb","twitter_card":"summary_large_image","twitter_creator":"@MCECleanEnergy","twitter_site":"@MCECleanEnergy","twitter_misc":{"\u00c9crit par":"Debbie Lamb","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mcecleanenergy.org\/young-leaders-in-action-mce-recognizes-young-bay-area-changemakers\/#article","isPartOf":{"@id":"https:\/\/mcecleanenergy.org\/young-leaders-in-action-mce-recognizes-young-bay-area-changemakers\/"},"author":{"name":"Debbie Lamb","@id":"https:\/\/mcecleanenergy.org\/#\/schema\/person\/529ce2d4ac862fbb09c6c0a9b0b952cd"},"headline":"Young Leaders in Action: MCE Recognizes Young Bay Area Changemakers","datePublished":"2026-05-07T16:00:00+00:00","dateModified":"2026-05-07T16:24:38+00:00","mainEntityOfPage":{"@id":"https:\/\/mcecleanenergy.org\/young-leaders-in-action-mce-recognizes-young-bay-area-changemakers\/"},"wordCount":1319,"publisher":{"@id":"https:\/\/mcecleanenergy.org\/#organization"},"image":{"@id":"https:\/\/mcecleanenergy.org\/young-leaders-in-action-mce-recognizes-young-bay-area-changemakers\/#primaryimage"},"thumbnailUrl":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2026\/05\/because-of-youth-2026-blog.png","keywords":["Bay Area","Renewable Energy","Sustainability"],"articleSection":["In the Community","Sustainability and Climate Action"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/mcecleanenergy.org\/young-leaders-in-action-mce-recognizes-young-bay-area-changemakers\/","url":"https:\/\/mcecleanenergy.org\/young-leaders-in-action-mce-recognizes-young-bay-area-changemakers\/","name":"Jeunes leaders en action : MCE r\u00e9compense les jeunes agents de changement de la Baie \u2013 Blog MCE","isPartOf":{"@id":"https:\/\/mcecleanenergy.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mcecleanenergy.org\/young-leaders-in-action-mce-recognizes-young-bay-area-changemakers\/#primaryimage"},"image":{"@id":"https:\/\/mcecleanenergy.org\/young-leaders-in-action-mce-recognizes-young-bay-area-changemakers\/#primaryimage"},"thumbnailUrl":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2026\/05\/because-of-youth-2026-blog.png","datePublished":"2026-05-07T16:00:00+00:00","dateModified":"2026-05-07T16:24:38+00:00","description":"MCE a r\u00e9cemment honor\u00e9 8 laur\u00e9ats de son premier prix d'impact \u00ab Gr\u00e2ce aux jeunes \u00bb reconnaissant de jeunes exceptionnels de la r\u00e9gion qui font une diff\u00e9rence significative par leur action environnementale et leur leadership dans leurs communaut\u00e9s.","breadcrumb":{"@id":"https:\/\/mcecleanenergy.org\/young-leaders-in-action-mce-recognizes-young-bay-area-changemakers\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mcecleanenergy.org\/young-leaders-in-action-mce-recognizes-young-bay-area-changemakers\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mcecleanenergy.org\/young-leaders-in-action-mce-recognizes-young-bay-area-changemakers\/#primaryimage","url":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2026\/05\/because-of-youth-2026-blog.png","contentUrl":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2026\/05\/because-of-youth-2026-blog.png","width":1180,"height":475,"caption":"Because of Youth Award Recipients 2026"},{"@type":"BreadcrumbList","@id":"https:\/\/mcecleanenergy.org\/young-leaders-in-action-mce-recognizes-young-bay-area-changemakers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mcecleanenergy.org\/"},{"@type":"ListItem","position":2,"name":"Young Leaders in Action: MCE Recognizes Young Bay Area Changemakers"}]},{"@type":"WebSite","@id":"https:\/\/mcecleanenergy.org\/#website","url":"https:\/\/mcecleanenergy.org\/","name":"MCE - \u00c9nergie de choix communautaire","description":"","publisher":{"@id":"https:\/\/mcecleanenergy.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mcecleanenergy.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mcecleanenergy.org\/#organization","name":"MCE","url":"https:\/\/mcecleanenergy.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mcecleanenergy.org\/#\/schema\/logo\/image\/","url":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/MCE_Logo_Full-Color_RGB_050324.png","contentUrl":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/MCE_Logo_Full-Color_RGB_050324.png","width":5001,"height":2986,"caption":"MCE"},"image":{"@id":"https:\/\/mcecleanenergy.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mceCleanEnergy\/","https:\/\/x.com\/MCECleanEnergy","https:\/\/www.instagram.com\/mcecleanenergy\/","https:\/\/www.linkedin.com\/company\/mcecleanenergy\/","https:\/\/www.youtube.com\/c\/Mcecleanenergy\/","https:\/\/en.wikipedia.org\/wiki\/Community_Choice_Aggregation#Marin_Clean_Energy"]},{"@type":"Person","@id":"https:\/\/mcecleanenergy.org\/#\/schema\/person\/529ce2d4ac862fbb09c6c0a9b0b952cd","name":"Debbie Lamb","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/c439b0a089c2fd256f9db2b902d716abcbed16d561521cc3bbf4dfa4a1cf2b5a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c439b0a089c2fd256f9db2b902d716abcbed16d561521cc3bbf4dfa4a1cf2b5a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c439b0a089c2fd256f9db2b902d716abcbed16d561521cc3bbf4dfa4a1cf2b5a?s=96&d=mm&r=g","caption":"Debbie Lamb"},"url":"https:\/\/mcecleanenergy.org\/fr\/author\/debbie\/"}]}},"_links":{"self":[{"href":"https:\/\/mcecleanenergy.org\/fr\/wp-json\/wp\/v2\/posts\/82734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mcecleanenergy.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mcecleanenergy.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mcecleanenergy.org\/fr\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/mcecleanenergy.org\/fr\/wp-json\/wp\/v2\/comments?post=82734"}],"version-history":[{"count":15,"href":"https:\/\/mcecleanenergy.org\/fr\/wp-json\/wp\/v2\/posts\/82734\/revisions"}],"predecessor-version":[{"id":82842,"href":"https:\/\/mcecleanenergy.org\/fr\/wp-json\/wp\/v2\/posts\/82734\/revisions\/82842"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mcecleanenergy.org\/fr\/wp-json\/wp\/v2\/media\/82839"}],"wp:attachment":[{"href":"https:\/\/mcecleanenergy.org\/fr\/wp-json\/wp\/v2\/media?parent=82734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mcecleanenergy.org\/fr\/wp-json\/wp\/v2\/categories?post=82734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mcecleanenergy.org\/fr\/wp-json\/wp\/v2\/tags?post=82734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}