{"id":40318,"date":"2022-04-26T09:59:21","date_gmt":"2022-04-26T16:59:21","guid":{"rendered":"https:\/\/mcecleanenergy.org\/national-bike-month-resources-to-get-riding\/"},"modified":"2024-05-31T17:58:41","modified_gmt":"2024-06-01T00:58:41","slug":"national-bike-month-resources-to-get-riding","status":"publish","type":"post","link":"https:\/\/mcecleanenergy.org\/pa\/national-bike-month-resources-to-get-riding\/","title":{"rendered":"\u0a30\u0a3e\u0a38\u0a3c\u0a1f\u0a30\u0a40 \u0a38\u0a3e\u0a08\u0a15\u0a32 \u0a2e\u0a39\u0a40\u0a28\u0a3e \u2014 \u0a38\u0a35\u0a3e\u0a30\u0a40 \u0a38\u0a3c\u0a41\u0a30\u0a42 \u0a15\u0a30\u0a28 \u0a32\u0a08 \u0a38\u0a30\u0a4b\u0a24"},"content":{"rendered":"<p>\u0a2e\u0a08 \u0a30\u0a3e\u0a38\u0a3c\u0a1f\u0a30\u0a40 \u0a38\u0a3e\u0a08\u0a15\u0a32 \u0a2e\u0a39\u0a40\u0a28\u0a3e \u0a39\u0a48! \u0a38\u0a3e\u0a08\u0a15\u0a32 \u0a24\u0a41\u0a39\u0a3e\u0a21\u0a47 \u0a15\u0a3e\u0a30\u0a2c\u0a28 \u0a2b\u0a41\u0a71\u0a1f\u0a2a\u0a4d\u0a30\u0a3f\u0a70\u0a1f \u0a28\u0a42\u0a70 \u0a18\u0a1f\u0a3e\u0a09\u0a23, \u0a38\u0a30\u0a17\u0a30\u0a2e \u0a30\u0a39\u0a3f\u0a23 \u0a05\u0a24\u0a47 \u0a06\u0a35\u0a3e\u0a1c\u0a3e\u0a08 \u0a26\u0a47 \u0a16\u0a30\u0a1a\u0a3f\u0a06\u0a02 \u0a28\u0a42\u0a70 \u0a18\u0a1f\u0a3e\u0a09\u0a23 \u0a32\u0a08 \u0a07\u0a71\u0a15 \u0a38\u0a3c\u0a15\u0a24\u0a40\u0a38\u0a3c\u0a3e\u0a32\u0a40 \u0a38\u0a3e\u0a27\u0a28 \u0a39\u0a28\u0964 \u0a2d\u0a3e\u0a35\u0a47\u0a02 \u0a24\u0a41\u0a38\u0a40\u0a02 \u0a2a\u0a39\u0a3f\u0a32\u0a40 \u0a35\u0a3e\u0a30 \u0a38\u0a3e\u0a08\u0a15\u0a32 \u0a16\u0a30\u0a40\u0a26 \u0a30\u0a39\u0a47 \u0a39\u0a4b, \u0a28\u0a35\u0a40\u0a02 \u0a38\u0a3e\u0a08\u0a15\u0a32 &#039;\u0a24\u0a47 \u0a05\u0a71\u0a2a\u0a17\u0a4d\u0a30\u0a47\u0a21 \u0a15\u0a30 \u0a30\u0a39\u0a47 \u0a39\u0a4b, \u0a1c\u0a3e\u0a02 \u0a08-\u0a2c\u0a3e\u0a08\u0a15 &#039;\u0a24\u0a47 \u0a38\u0a35\u0a3f\u0a1a \u0a15\u0a30 \u0a30\u0a39\u0a47 \u0a39\u0a4b, \u0a07\u0a71\u0a25\u0a47 \u0a38\u0a35\u0a3e\u0a30\u0a40 \u0a32\u0a08 \u0a15\u0a41\u0a1d \u0a38\u0a30\u0a4b\u0a24 \u0a39\u0a28\u0964<\/p>\n<p><strong>\u0a2e\u0a3e\u0a08\u0a15\u0a38 \u0a2c\u0a3e\u0a08\u0a15\u0a38<\/strong><\/p>\n<p><a href=\"https:\/\/mikesbikes.com\/\" target=\"_blank\" rel=\"noopener\">\u0a2e\u0a3e\u0a08\u0a15 \u0a26\u0a40\u0a06\u0a02 \u0a2c\u0a3e\u0a08\u0a15\u0a38<\/a> \u0a07\u0a39 \u0a2c\u0a3e\u0a08\u0a15 \u0a26\u0a40\u0a06\u0a02 \u0a26\u0a41\u0a15\u0a3e\u0a28\u0a3e\u0a02 \u0a26\u0a3e \u0a07\u0a71\u0a15 \u0a2a\u0a30\u0a3f\u0a35\u0a3e\u0a30 \u0a39\u0a48 \u0a05\u0a24\u0a47 MCE \u0a26\u0a47 Deep Green \u0a1a\u0a48\u0a02\u0a2a\u0a40\u0a05\u0a28\u0a3e\u0a02 \u0a35\u0a3f\u0a71\u0a1a\u0a4b\u0a02 \u0a07\u0a71\u0a15 \u0a39\u0a48 \u0a1c\u0a4b 100% \u0a28\u0a35\u0a3f\u0a06\u0a09\u0a23\u0a2f\u0a4b\u0a17 \u0a0a\u0a30\u0a1c\u0a3e &#039;\u0a24\u0a47 \u0a15\u0a70\u0a2e \u0a15\u0a30\u0a26\u0a3e \u0a39\u0a48\u0964 1964 \u0a35\u0a3f\u0a71\u0a1a \u0a38\u0a25\u0a3e\u0a2a\u0a3f\u0a24, \u0a2e\u0a3e\u0a08\u0a15\u0a1c\u0a3c \u0a2c\u0a3e\u0a08\u0a15\u0a38 \u0a38\u0a48\u0a28 \u0a30\u0a3e\u0a2b\u0a47\u0a32 \u0a38\u0a25\u0a3e\u0a28 \u0a26\u0a47\u0a38\u0a3c \u0a35\u0a3f\u0a71\u0a1a \u0a15\u0a41\u0a1d \u0a2a\u0a39\u0a3f\u0a32\u0a47 \u0a2a\u0a39\u0a3e\u0a5c\u0a40 \u0a2c\u0a3e\u0a08\u0a15\u0a3e\u0a02 \u0a26\u0a3e \u0a18\u0a30 \u0a39\u0a48\u0964 \u0a15\u0a70\u0a2a\u0a28\u0a40 \u0a09\u0a26\u0a4b\u0a02 \u0a24\u0a4b\u0a02 \u0a05\u0a2e\u0a30\u0a40\u0a15\u0a3e \u0a35\u0a3f\u0a71\u0a1a \u0a38\u0a2d \u0a24\u0a4b\u0a02 \u0a35\u0a71\u0a21\u0a40 \u0a38\u0a41\u0a24\u0a70\u0a24\u0a30 \u0a2c\u0a3e\u0a08\u0a15 \u0a21\u0a40\u0a32\u0a30 \u0a2c\u0a23 \u0a17\u0a08 \u0a39\u0a48 \u0a05\u0a24\u0a47 \u0a07\u0a38 \u0a26\u0a47 \u0a2c\u0a47 \u0a0f\u0a30\u0a40\u0a06 \u0a35\u0a3f\u0a71\u0a1a 12 \u0a38\u0a25\u0a3e\u0a28 \u0a39\u0a28, \u0a1c\u0a3f\u0a38 \u0a35\u0a3f\u0a71\u0a1a \u0a38\u0a48\u0a28 \u0a30\u0a3e\u0a2b\u0a47\u0a32, \u0a38\u0a4c\u0a38\u0a3e\u0a32\u0a3f\u0a1f\u0a4b \u0a05\u0a24\u0a47 \u0a35\u0a3e\u0a32\u0a28\u0a1f \u0a15\u0a4d\u0a30\u0a40\u0a15 \u0a38\u0a3c\u0a3e\u0a2e\u0a32 \u0a39\u0a28\u0964 \u0a2c\u0a3e\u0a08\u0a15 \u0a2e\u0a3e\u0a39\u0a30\u0a3e\u0a02 \u0a28\u0a3e\u0a32 \u0a17\u0a71\u0a32\u0a2c\u0a3e\u0a24 \u0a15\u0a30\u0a28 \u0a05\u0a24\u0a47 \u0a38\u0a5c\u0a15, \u0a2a\u0a39\u0a3e\u0a5c\u0a40, \u0a38\u0a30\u0a17\u0a30\u0a2e, \u0a2c\u0a71\u0a1a\u0a3f\u0a06\u0a02 \u0a05\u0a24\u0a47 \u0a07\u0a32\u0a48\u0a15\u0a1f\u0a4d\u0a30\u0a3f\u0a15 \u0a2c\u0a3e\u0a08\u0a15\u0a3e\u0a02 \u0a26\u0a40 \u0a09\u0a28\u0a4d\u0a39\u0a3e\u0a02 \u0a26\u0a40 \u0a35\u0a3f\u0a38\u0a3c\u0a3e\u0a32 \u0a1a\u0a4b\u0a23 \u0a26\u0a40 \u0a1c\u0a3e\u0a02\u0a1a \u0a15\u0a30\u0a28 \u0a32\u0a08 \u0a09\u0a28\u0a4d\u0a39\u0a3e\u0a02 \u0a26\u0a40\u0a06\u0a02 \u0a26\u0a41\u0a15\u0a3e\u0a28\u0a3e\u0a02 \u0a35\u0a3f\u0a71\u0a1a\u0a4b\u0a02 \u0a07\u0a71\u0a15 &#039;\u0a24\u0a47 \u0a1c\u0a3e\u0a13\u0964<\/p>\n<p>https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2020\/10\/mikes-bikes-map.jpg<\/p>\n<blockquote><p>\u201c\u0a2e\u0a3e\u0a08\u0a15&#039;\u0a1c\u0a3c \u0a2c\u0a3e\u0a08\u0a15\u0a38 \u0a35\u0a3f\u0a16\u0a47, \u0a38\u0a3e\u0a21\u0a3e \u0a2e\u0a3f\u0a38\u0a3c\u0a28 \u0a38\u0a30\u0a32 \u0a39\u0a48: \u0a2c\u0a3e\u0a08\u0a15 &#039;\u0a24\u0a47 \u0a39\u0a4b\u0a30 \u0a32\u0a4b\u0a15\u0a3e\u0a02 \u0a28\u0a42\u0a70 \u0a38\u0a3c\u0a3e\u0a2e\u0a32 \u0a15\u0a30\u0a4b! 1964 \u0a24\u0a4b\u0a02, \u0a38\u0a3e\u0a21\u0a3e \u0a2a\u0a42\u0a30\u0a3e \u0a15\u0a3e\u0a30\u0a4b\u0a2c\u0a3e\u0a30 \u0a39\u0a41\u0a23 \u0a24\u0a71\u0a15 \u0a2c\u0a23\u0a3e\u0a0f \u0a17\u0a0f \u0a38\u0a2d \u0a24\u0a4b\u0a02 \u0a35\u0a3e\u0a24\u0a3e\u0a35\u0a30\u0a23\u0a15 \u0a05\u0a24\u0a47 \u0a1f\u0a3f\u0a15\u0a3e\u0a0a \u0a35\u0a3e\u0a39\u0a28 \u23af \u0a38\u0a3e\u0a08\u0a15\u0a32 &#039;\u0a24\u0a47 \u0a05\u0a27\u0a3e\u0a30\u0a24 \u0a30\u0a3f\u0a39\u0a3e \u0a39\u0a48\u0964 \u0a05\u0a38\u0a40\u0a02 \u0a38\u0a3e\u0a08\u0a15\u0a32 \u0a1f\u0a3f\u0a0a\u0a2c\u0a3e\u0a02 \u0a28\u0a42\u0a70 \u0a30\u0a40\u0a38\u0a3e\u0a08\u0a15\u0a32 \u0a15\u0a30\u0a26\u0a47 \u0a39\u0a3e\u0a02, \u0a06\u0a2a\u0a23\u0a47 \u0a24\u0a15\u0a28\u0a40\u0a15\u0a40 \u0a35\u0a3f\u0a2d\u0a3e\u0a17\u0a3e\u0a02 \u0a35\u0a3f\u0a71\u0a1a \u0a35\u0a3e\u0a24\u0a3e\u0a35\u0a30\u0a23 \u0a05\u0a28\u0a41\u0a15\u0a42\u0a32 \u0a32\u0a41\u0a2c\u0a30\u0a40\u0a15\u0a48\u0a02\u0a1f \u0a05\u0a24\u0a47 \u0a15\u0a32\u0a40\u0a28\u0a30 \u0a26\u0a40 \u0a35\u0a30\u0a24\u0a4b\u0a02 \u0a15\u0a30\u0a26\u0a47 \u0a39\u0a3e\u0a02, \u0a05\u0a24\u0a47 \u0a06\u0a2a\u0a23\u0a47 \u0a15\u0a30\u0a2e\u0a1a\u0a3e\u0a30\u0a40\u0a06\u0a02 \u0a28\u0a42\u0a70 \u0a17\u0a71\u0a21\u0a40 \u0a1a\u0a32\u0a3e\u0a09\u0a23 \u0a26\u0a40 \u0a2c\u0a1c\u0a3e\u0a0f \u0a38\u0a35\u0a3e\u0a30\u0a40 \u0a32\u0a08 \u0a2d\u0a41\u0a17\u0a24\u0a3e\u0a28 \u0a15\u0a30\u0a26\u0a47 \u0a39\u0a3e\u0a02\u0964 \u0a38\u0a3e\u0a21\u0a40\u0a06\u0a02 \u0a26\u0a41\u0a15\u0a3e\u0a28\u0a3e\u0a02 \u0a32\u0a08 Deep Green \u0a1c\u0a3e\u0a23\u0a3e \u0a38\u0a3e\u0a08\u0a15\u0a32 \u0a1a\u0a32\u0a3e\u0a09\u0a23 \u0a1c\u0a3f\u0a70\u0a28\u0a3e \u0a06\u0a38\u0a3e\u0a28 \u0a38\u0a40\u0964\u201d \u2014 \u0a0f\u0a30\u0a3f\u0a15 \u0a32\u0a42\u0a15\u0a28, \u0a2e\u0a3e\u0a08\u0a15&#039;\u0a1c\u0a3c \u0a2c\u0a3e\u0a08\u0a15\u0a38 \u0a26\u0a47 \u0a2e\u0a41\u0a71\u0a16 \u0a2e\u0a3e\u0a30\u0a15\u0a40\u0a1f\u0a3f\u0a70\u0a17 \u0a05\u0a27\u0a3f\u0a15\u0a3e\u0a30\u0a40<\/p><\/blockquote>\n<p><strong>\u0a28\u0a35\u0a3e\u0a02 \u0a2a\u0a39\u0a40\u0a06<\/strong><\/p>\n<p><a href=\"https:\/\/newwheel.net\/electric-bike-basics\" target=\"_blank\" rel=\"noopener\">\u0a28\u0a35\u0a3e\u0a02 \u0a2a\u0a39\u0a40\u0a06<\/a> \u0a07\u0a71\u0a15 \u0a07\u0a32\u0a48\u0a15\u0a1f\u0a4d\u0a30\u0a3f\u0a15 \u0a2c\u0a3e\u0a08\u0a15 \u0a30\u0a3f\u0a1f\u0a47\u0a32\u0a30 \u0a39\u0a48 \u0a1c\u0a4b MCE \u0a26\u0a47 Deep Green 100% \u0a28\u0a35\u0a3f\u0a06\u0a09\u0a23\u0a2f\u0a4b\u0a17 \u0a0a\u0a30\u0a1c\u0a3e &#039;\u0a24\u0a47 \u0a1a\u0a71\u0a32\u0a26\u0a3e \u0a39\u0a48\u0964 2010 \u0a35\u0a3f\u0a71\u0a1a, \u0a15\u0a48\u0a30\u0a28 \u0a35\u0a47\u0a28\u0a30 \u0a28\u0a47 \u0a06\u0a35\u0a3e\u0a1c\u0a3e\u0a08 \u0a28\u0a42\u0a70 \u0a2c\u0a26\u0a32\u0a23 \u0a05\u0a24\u0a47 \u0a1c\u0a32\u0a35\u0a3e\u0a2f\u0a42 \u0a2a\u0a30\u0a3f\u0a35\u0a30\u0a24\u0a28 \u0a28\u0a3e\u0a32 \u0a32\u0a5c\u0a28 \u0a32\u0a08 \u0a15\u0a70\u0a2e \u0a15\u0a30\u0a28 \u0a26\u0a47 \u0a26\u0a4d\u0a30\u0a3f\u0a38\u0a3c\u0a1f\u0a40\u0a15\u0a4b\u0a23 \u0a28\u0a3e\u0a32 \u0a26 \u0a28\u0a3f\u0a0a \u0a35\u0a4d\u0a39\u0a40\u0a32 \u0a26\u0a40 \u0a38\u0a25\u0a3e\u0a2a\u0a28\u0a3e \u0a15\u0a40\u0a24\u0a40\u0964 \u0a15\u0a40 \u0a24\u0a41\u0a38\u0a40\u0a02 \u0a08-\u0a2c\u0a3e\u0a08\u0a15 \u0a2c\u0a3e\u0a30\u0a47 \u0a38\u0a4b\u0a1a \u0a30\u0a39\u0a47 \u0a39\u0a4b? \u0a26 \u0a28\u0a3f\u0a0a \u0a35\u0a4d\u0a39\u0a40\u0a32 \u0a08-\u0a2c\u0a3e\u0a08\u0a15 \u0a26\u0a47 \u0a06\u0a2a\u0a23\u0a47 \u0a21\u0a48\u0a2e\u0a4b \u0a2b\u0a32\u0a40\u0a1f &#039;\u0a24\u0a47 \u0a1f\u0a48\u0a38\u0a1f \u0a30\u0a3e\u0a08\u0a21 \u0a26\u0a40 \u0a2a\u0a47\u0a38\u0a3c\u0a15\u0a38\u0a3c \u0a15\u0a30\u0a26\u0a3e \u0a39\u0a48\u0964 \u0a38\u0a48\u0a28 \u0a30\u0a3e\u0a2b\u0a47\u0a32, \u0a38\u0a48\u0a28 \u0a2b\u0a30\u0a3e\u0a02\u0a38\u0a3f\u0a38\u0a15\u0a4b, \u0a1c\u0a3e\u0a02 \u0a13\u0a15\u0a32\u0a48\u0a02\u0a21 \u0a35\u0a3f\u0a71\u0a1a \u0a09\u0a28\u0a4d\u0a39\u0a3e\u0a02 \u0a26\u0a40 \u0a26\u0a41\u0a15\u0a3e\u0a28 &#039;\u0a24\u0a47 \u0a1c\u0a3e\u0a13 \u0a05\u0a24\u0a47 \u0a26\u0a47\u0a16\u0a4b \u0a15\u0a3f \u0a15\u0a40 \u0a15\u0a4b\u0a08 \u0a08-\u0a2c\u0a3e\u0a08\u0a15 \u0a24\u0a41\u0a39\u0a3e\u0a21\u0a47 \u0a32\u0a08 \u0a38\u0a39\u0a40 \u0a39\u0a48!<\/p>\n<p>https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2020\/10\/the-new-wheel-map.jpg<\/p>\n<blockquote><p>&quot;\u0a38\u0a3e\u0a2b\u0a3c, \u0a39\u0a30\u0a47 \u0a07\u0a32\u0a48\u0a15\u0a1f\u0a4d\u0a30\u0a3f\u0a15 \u0a2c\u0a3e\u0a08\u0a15\u0a3e\u0a02 \u0a26\u0a47 \u0a07\u0a71\u0a15 \u0a2a\u0a4d\u0a30\u0a1a\u0a42\u0a28 \u0a35\u0a3f\u0a15\u0a30\u0a47\u0a24\u0a3e \u0a26\u0a47 \u0a30\u0a42\u0a2a \u0a35\u0a3f\u0a71\u0a1a, \u0a26 \u0a28\u0a3f\u0a0a \u0a35\u0a4d\u0a39\u0a40\u0a32 \u0a1c\u0a32\u0a35\u0a3e\u0a2f\u0a42 \u0a2a\u0a30\u0a3f\u0a35\u0a30\u0a24\u0a28 \u0a26\u0a3e \u0a2e\u0a41\u0a15\u0a3e\u0a2c\u0a32\u0a3e \u0a15\u0a30\u0a28 \u0a05\u0a24\u0a47 \u0a35\u0a27\u0a47\u0a30\u0a47 \u0a1f\u0a3f\u0a15\u0a3e\u0a0a \u0a1c\u0a40\u0a35\u0a28 \u0a1c\u0a3f\u0a09\u0a23 \u0a32\u0a08 \u0a35\u0a1a\u0a28\u0a2c\u0a71\u0a27 \u0a39\u0a48\u0964 \u0a05\u0a38\u0a40\u0a02 \u0a09\u0a38 \u0a1a\u0a40\u0a1c\u0a3c \u0a26\u0a40 \u0a15\u0a26\u0a30 \u0a15\u0a30\u0a26\u0a47 \u0a39\u0a3e\u0a02 \u0a1c\u0a3f\u0a38\u0a28\u0a42\u0a70 MCE \u0a1f\u0a3f\u0a15\u0a3e\u0a0a \u0a1c\u0a40\u0a35\u0a28 \u0a32\u0a08 \u0a07\u0a71\u0a15 \u0a38\u0a25\u0a3e\u0a28\u0a15 \u0a05\u0a24\u0a47 \u0a1c\u0a28\u0a24\u0a15 \u0a38\u0a3c\u0a15\u0a24\u0a40 \u0a35\u0a1c\u0a4b\u0a02 \u0a26\u0a30\u0a38\u0a3e\u0a09\u0a02\u0a26\u0a3e \u0a39\u0a48 \u0a05\u0a24\u0a47 \u0a07\u0a39 \u0a1a\u0a41\u0a23\u0a28 \u0a26\u0a40 \u0a2f\u0a4b\u0a17\u0a24\u0a3e \u0a2a\u0a4d\u0a30\u0a3e\u0a2a\u0a24 \u0a15\u0a30\u0a15\u0a47 \u0a2c\u0a39\u0a41\u0a24 \u0a16\u0a41\u0a38\u0a3c \u0a39\u0a3e\u0a02 \u0a15\u0a3f \u0a38\u0a3e\u0a21\u0a40\u0a06\u0a02 \u0a32\u0a3e\u0a08\u0a1f\u0a3e\u0a02 \u0a05\u0a24\u0a47 \u0a38\u0a3e\u0a21\u0a40\u0a06\u0a02 \u0a08-\u0a2c\u0a3e\u0a08\u0a15\u0a3e\u0a02 \u0a28\u0a42\u0a70 \u0a38\u0a3c\u0a15\u0a24\u0a40 \u0a26\u0a47\u0a23 \u0a35\u0a3e\u0a32\u0a40 \u0a0a\u0a30\u0a1c\u0a3e \u0a15\u0a3f\u0a35\u0a47\u0a02 \u0a2a\u0a48\u0a26\u0a3e \u0a15\u0a40\u0a24\u0a40 \u0a1c\u0a3e\u0a02\u0a26\u0a40 \u0a39\u0a48\u0964&quot; \u2014 \u0a2c\u0a4d\u0a30\u0a48\u0a1f \u0a25\u0a30\u0a2c\u0a30, \u0a26 \u0a28\u0a3f\u0a0a \u0a35\u0a4d\u0a39\u0a40\u0a32 \u0a13\u0a28\u0a30<\/p><\/blockquote>\n<p><strong>\u0a1a\u0a3e\u0a30\u0a1c \u0a05\u0a71\u0a2a \u0a15\u0a70\u0a1f\u0a30\u0a3e \u0a15\u0a4b\u0a38\u0a1f\u0a3e<\/strong><\/p>\n<p>\u0a08-\u0a2c\u0a3e\u0a08\u0a15 \u0a39\u0a30 \u0a09\u0a2e\u0a30 \u0a05\u0a24\u0a47 \u0a24\u0a70\u0a26\u0a30\u0a41\u0a38\u0a24\u0a40 \u0a2a\u0a71\u0a27\u0a30 \u0a26\u0a47 \u0a32\u0a4b\u0a15\u0a3e\u0a02 \u0a32\u0a08 \u0a06\u0a09\u0a23-\u0a1c\u0a3e\u0a23 \u0a05\u0a24\u0a47 \u0a2e\u0a28\u0a4b\u0a30\u0a70\u0a1c\u0a28 \u0a32\u0a08 \u0a07\u0a71\u0a15 \u0a35\u0a27\u0a40\u0a06 \u0a35\u0a3f\u0a15\u0a32\u0a2a \u0a39\u0a28\u0964 \u0a09\u0a28\u0a4d\u0a39\u0a3e\u0a02 \u0a26\u0a40\u0a06\u0a02 \u0a30\u0a40\u0a1a\u0a3e\u0a30\u0a1c \u0a39\u0a4b\u0a23 \u0a2f\u0a4b\u0a17, \u0a2c\u0a48\u0a1f\u0a30\u0a40 \u0a28\u0a3e\u0a32 \u0a1a\u0a71\u0a32\u0a23 \u0a35\u0a3e\u0a32\u0a40\u0a06\u0a02 \u0a07\u0a32\u0a48\u0a15\u0a1f\u0a4d\u0a30\u0a3f\u0a15 \u0a2e\u0a4b\u0a1f\u0a30\u0a3e\u0a02 \u0a06\u0a38\u0a3e\u0a28\u0a40 \u0a28\u0a3e\u0a32 \u0a09\u0a71\u0a2a\u0a30 \u0a35\u0a71\u0a32 \u0a38\u0a35\u0a3e\u0a30\u0a40 \u0a15\u0a30\u0a28\u0a3e \u0a38\u0a70\u0a2d\u0a35 \u0a2c\u0a23\u0a3e\u0a09\u0a02\u0a26\u0a40\u0a06\u0a02 \u0a39\u0a28\u0964<\/p>\n<p>\u0a1a\u0a3e\u0a30\u0a1c \u0a05\u0a71\u0a2a \u0a15\u0a4c\u0a02\u0a1f\u0a30\u0a3e \u0a15\u0a4b\u0a38\u0a1f\u0a3e \u0a08-\u0a2c\u0a3e\u0a08\u0a15 \u0a16\u0a30\u0a40\u0a26\u0a23 \u0a28\u0a42\u0a70 \u0a39\u0a4b\u0a30 \u0a15\u0a3f\u0a2b\u0a3e\u0a07\u0a24\u0a40 \u0a2c\u0a23\u0a3e\u0a09\u0a23 \u0a32\u0a08 \u0a1b\u0a4b\u0a1f\u0a3e\u0a02 \u0a26\u0a40 \u0a2a\u0a47\u0a38\u0a3c\u0a15\u0a38\u0a3c \u0a15\u0a30\u0a26\u0a3e \u0a39\u0a48\u0964 18 \u0a38\u0a3e\u0a32 \u0a1c\u0a3e\u0a02 \u0a07\u0a38 \u0a24\u0a4b\u0a02 \u0a35\u0a71\u0a27 \u0a09\u0a2e\u0a30 \u0a26\u0a47 \u0a28\u0a3f\u0a35\u0a3e\u0a38\u0a40 \u0a28\u0a35\u0a40\u0a02 \u0a08-\u0a2c\u0a3e\u0a08\u0a15 \u0a16\u0a30\u0a40\u0a26\u0a23 \u0a32\u0a08 $500 \u0a1b\u0a4b\u0a1f \u0a32\u0a08 \u0a2f\u0a4b\u0a17 \u0a39\u0a28\u0964 \u0a09\u0a39\u0a28\u0a3e\u0a02 \u0a28\u0a42\u0a70 \u0a15\u0a4c\u0a28\u0a15\u0a4c\u0a30\u0a21 \u0a26\u0a47 \u0a38\u0a2e\u0a3e\u0a30\u0a15 \u0a15\u0a4b\u0a30\u0a40\u0a21\u0a4b\u0a30, \u0a30\u0a3f\u0a1a\u0a2e\u0a70\u0a21, \u0a2a\u0a3f\u0a1f\u0a38\u0a2c\u0a30\u0a17, \u0a1c\u0a3e\u0a02 \u0a2c\u0a47 \u0a2a\u0a41\u0a06\u0a07\u0a70\u0a1f \u0a35\u0a3f\u0a71\u0a1a \u0a30\u0a39\u0a3f\u0a23\u0a3e \u0a1a\u0a3e\u0a39\u0a40\u0a26\u0a3e \u0a39\u0a48 \u0a05\u0a24\u0a47 \u0a2f\u0a4b\u0a17 \u0a38\u0a3e\u0a32\u0a3e\u0a28\u0a3e \u0a18\u0a30\u0a47\u0a32\u0a42 \u0a06\u0a2e\u0a26\u0a28 \u0a38\u0a40\u0a2e\u0a3e\u0a35\u0a3e\u0a02 \u0a28\u0a42\u0a70 \u0a2a\u0a42\u0a30\u0a3e \u0a15\u0a30\u0a28\u0a3e \u0a1a\u0a3e\u0a39\u0a40\u0a26\u0a3e \u0a39\u0a48\u0964 \u0a39\u0a4b\u0a30 \u0a1c\u0a3e\u0a23\u0a4b <a href=\"http:\/\/ccta.net\/projects\/charge-up\/e-bike-rebate-program\/\" target=\"_blank\" rel=\"noopener\">\u0a07\u0a25\u0a47<\/a>.<\/p>\n<p>\u0a38\u0a3e\u0a28\u0a42\u0a70 \u0a09\u0a2e\u0a40\u0a26 \u0a39\u0a48 \u0a15\u0a3f \u0a07\u0a39 \u0a38\u0a30\u0a4b\u0a24 \u0a24\u0a41\u0a39\u0a3e\u0a21\u0a40 \u0a38\u0a3e\u0a08\u0a15\u0a32 \u0a28\u0a42\u0a70 \u0a1a\u0a32\u0a3e\u0a09\u0a23 \u0a35\u0a3f\u0a71\u0a1a \u0a2e\u0a26\u0a26 \u0a15\u0a30\u0a28\u0a17\u0a47! \u0a26\u0a47\u0a16\u0a4b\u0964 <a href=\"https:\/\/bayareabiketowork.com\/\" target=\"_blank\" rel=\"noopener\">\u0a2c\u0a47 \u0a0f\u0a30\u0a40\u0a06 \u0a2c\u0a3e\u0a08\u0a15 \u0a1f\u0a42 \u0a35\u0a40\u0a35\u0a47\u0a05\u0a30 \u0a21\u0a47\u0a1c\u0a3c<\/a> \u0a2c\u0a3e\u0a08\u0a15 \u0a2e\u0a39\u0a40\u0a28\u0a47 \u0a26\u0a4c\u0a30\u0a3e\u0a28 \u0a24\u0a41\u0a39\u0a3e\u0a21\u0a47 \u0a07\u0a32\u0a3e\u0a15\u0a47 \u0a35\u0a3f\u0a71\u0a1a \u0a39\u0a4b\u0a23 \u0a35\u0a3e\u0a32\u0a47 \u0a2c\u0a3e\u0a08\u0a15\u0a3f\u0a70\u0a17 \u0a38\u0a2e\u0a3e\u0a17\u0a2e\u0a3e\u0a02 \u0a2c\u0a3e\u0a30\u0a47 \u0a1c\u0a3e\u0a23\u0a28 \u0a32\u0a08\u0964<\/p>","protected":false},"excerpt":{"rendered":"<p>May is National Bike Month! Bikes are a powerful tool to lower your carbon footprint, stay active, and reduce transportation costs. Whether you\u2019re purchasing a bike for the first time, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":40319,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_searchwp_excluded":"","footnotes":""},"categories":[825,823],"tags":[],"class_list":["post-40318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-clean-transportation","category-sustainability-and-climate-action"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>National Bike Month \u2014 Resources to Get Riding - MCE Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mcecleanenergy.org\/pa\/national-bike-month-resources-to-get-riding\/\" \/>\n<meta property=\"og:locale\" content=\"pa_IN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"National Bike Month \u2014 Resources to Get Riding\" \/>\n<meta property=\"og:description\" content=\"May is National Bike Month! Bikes are a powerful tool to lower your carbon footprint, stay active, and reduce transportation costs. Whether you\u2019re\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mcecleanenergy.org\/pa\/national-bike-month-resources-to-get-riding\/\" \/>\n<meta property=\"og:site_name\" content=\"MCE \u2013 Community Choice Energy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mceCleanEnergy\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-26T16:59:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-01T00:58:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/national-bike-month.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Rohan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MCECleanEnergy\" \/>\n<meta name=\"twitter:site\" content=\"@MCECleanEnergy\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rohan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/national-bike-month-resources-to-get-riding\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/national-bike-month-resources-to-get-riding\\\/\"},\"author\":{\"name\":\"Rohan\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#\\\/schema\\\/person\\\/8ce2f62799413aaa2b6868dc9b471748\"},\"headline\":\"National Bike Month \u2014 Resources to Get Riding\",\"datePublished\":\"2022-04-26T16:59:21+00:00\",\"dateModified\":\"2024-06-01T00:58:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/national-bike-month-resources-to-get-riding\\\/\"},\"wordCount\":491,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/national-bike-month-resources-to-get-riding\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/national-bike-month.png\",\"articleSection\":[\"Clean Transportation\",\"Sustainability and Climate Action\"],\"inLanguage\":\"pa-IN\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mcecleanenergy.org\\\/national-bike-month-resources-to-get-riding\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/national-bike-month-resources-to-get-riding\\\/\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/national-bike-month-resources-to-get-riding\\\/\",\"name\":\"National Bike Month \u2014 Resources to Get Riding - MCE Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/national-bike-month-resources-to-get-riding\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/national-bike-month-resources-to-get-riding\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/national-bike-month.png\",\"datePublished\":\"2022-04-26T16:59:21+00:00\",\"dateModified\":\"2024-06-01T00:58:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/national-bike-month-resources-to-get-riding\\\/#breadcrumb\"},\"inLanguage\":\"pa-IN\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mcecleanenergy.org\\\/national-bike-month-resources-to-get-riding\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pa-IN\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/national-bike-month-resources-to-get-riding\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/national-bike-month.png\",\"contentUrl\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/national-bike-month.png\",\"width\":1100,\"height\":440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/national-bike-month-resources-to-get-riding\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mcecleanenergy.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"National Bike Month \u2014 Resources to Get Riding\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#website\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/\",\"name\":\"MCE \u2013 Community Choice Energy\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mcecleanenergy.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pa-IN\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#organization\",\"name\":\"MCE\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pa-IN\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/MCE_Logo_Full-Color_RGB_050324.png\",\"contentUrl\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/MCE_Logo_Full-Color_RGB_050324.png\",\"width\":5001,\"height\":2986,\"caption\":\"MCE\"},\"image\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mceCleanEnergy\\\/\",\"https:\\\/\\\/x.com\\\/MCECleanEnergy\",\"https:\\\/\\\/www.instagram.com\\\/mcecleanenergy\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mcecleanenergy\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/Mcecleanenergy\\\/\",\"https:\\\/\\\/en.wikipedia.org\\\/wiki\\\/Community_Choice_Aggregation#Marin_Clean_Energy\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#\\\/schema\\\/person\\\/8ce2f62799413aaa2b6868dc9b471748\",\"name\":\"Rohan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pa-IN\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/08c0249ed3a34e3695a3cb94fc48aa840d636d2ba6af19ac1dd65e5303c3c992?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/08c0249ed3a34e3695a3cb94fc48aa840d636d2ba6af19ac1dd65e5303c3c992?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/08c0249ed3a34e3695a3cb94fc48aa840d636d2ba6af19ac1dd65e5303c3c992?s=96&d=mm&r=g\",\"caption\":\"Rohan\"},\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/pa\\\/author\\\/rohan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"National Bike Month \u2014 Resources to Get Riding - MCE Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mcecleanenergy.org\/pa\/national-bike-month-resources-to-get-riding\/","og_locale":"pa_IN","og_type":"article","og_title":"National Bike Month \u2014 Resources to Get Riding","og_description":"May is National Bike Month! Bikes are a powerful tool to lower your carbon footprint, stay active, and reduce transportation costs. Whether you\u2019re","og_url":"https:\/\/mcecleanenergy.org\/pa\/national-bike-month-resources-to-get-riding\/","og_site_name":"MCE \u2013 Community Choice Energy","article_publisher":"https:\/\/www.facebook.com\/mceCleanEnergy\/","article_published_time":"2022-04-26T16:59:21+00:00","article_modified_time":"2024-06-01T00:58:41+00:00","og_image":[{"width":1100,"height":440,"url":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/national-bike-month.png","type":"image\/png"}],"author":"Rohan","twitter_card":"summary_large_image","twitter_creator":"@MCECleanEnergy","twitter_site":"@MCECleanEnergy","twitter_misc":{"Written by":"Rohan","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mcecleanenergy.org\/national-bike-month-resources-to-get-riding\/#article","isPartOf":{"@id":"https:\/\/mcecleanenergy.org\/national-bike-month-resources-to-get-riding\/"},"author":{"name":"Rohan","@id":"https:\/\/mcecleanenergy.org\/#\/schema\/person\/8ce2f62799413aaa2b6868dc9b471748"},"headline":"National Bike Month \u2014 Resources to Get Riding","datePublished":"2022-04-26T16:59:21+00:00","dateModified":"2024-06-01T00:58:41+00:00","mainEntityOfPage":{"@id":"https:\/\/mcecleanenergy.org\/national-bike-month-resources-to-get-riding\/"},"wordCount":491,"commentCount":0,"publisher":{"@id":"https:\/\/mcecleanenergy.org\/#organization"},"image":{"@id":"https:\/\/mcecleanenergy.org\/national-bike-month-resources-to-get-riding\/#primaryimage"},"thumbnailUrl":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/national-bike-month.png","articleSection":["Clean Transportation","Sustainability and Climate Action"],"inLanguage":"pa-IN","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mcecleanenergy.org\/national-bike-month-resources-to-get-riding\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mcecleanenergy.org\/national-bike-month-resources-to-get-riding\/","url":"https:\/\/mcecleanenergy.org\/national-bike-month-resources-to-get-riding\/","name":"National Bike Month \u2014 Resources to Get Riding - MCE Blog","isPartOf":{"@id":"https:\/\/mcecleanenergy.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mcecleanenergy.org\/national-bike-month-resources-to-get-riding\/#primaryimage"},"image":{"@id":"https:\/\/mcecleanenergy.org\/national-bike-month-resources-to-get-riding\/#primaryimage"},"thumbnailUrl":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/national-bike-month.png","datePublished":"2022-04-26T16:59:21+00:00","dateModified":"2024-06-01T00:58:41+00:00","breadcrumb":{"@id":"https:\/\/mcecleanenergy.org\/national-bike-month-resources-to-get-riding\/#breadcrumb"},"inLanguage":"pa-IN","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mcecleanenergy.org\/national-bike-month-resources-to-get-riding\/"]}]},{"@type":"ImageObject","inLanguage":"pa-IN","@id":"https:\/\/mcecleanenergy.org\/national-bike-month-resources-to-get-riding\/#primaryimage","url":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/national-bike-month.png","contentUrl":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/national-bike-month.png","width":1100,"height":440},{"@type":"BreadcrumbList","@id":"https:\/\/mcecleanenergy.org\/national-bike-month-resources-to-get-riding\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mcecleanenergy.org\/"},{"@type":"ListItem","position":2,"name":"National Bike Month \u2014 Resources to Get Riding"}]},{"@type":"WebSite","@id":"https:\/\/mcecleanenergy.org\/#website","url":"https:\/\/mcecleanenergy.org\/","name":"MCE - \u0a15\u0a2e\u0a3f\u0a0a\u0a28\u0a3f\u0a1f\u0a40 \u0a1a\u0a41\u0a06\u0a07\u0a38 \u0a10\u0a28\u0a30\u0a1c\u0a40","description":"","publisher":{"@id":"https:\/\/mcecleanenergy.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mcecleanenergy.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pa-IN"},{"@type":"Organization","@id":"https:\/\/mcecleanenergy.org\/#organization","name":"\u0a10\u0a2e.\u0a38\u0a40.\u0a08.","url":"https:\/\/mcecleanenergy.org\/","logo":{"@type":"ImageObject","inLanguage":"pa-IN","@id":"https:\/\/mcecleanenergy.org\/#\/schema\/logo\/image\/","url":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/MCE_Logo_Full-Color_RGB_050324.png","contentUrl":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/MCE_Logo_Full-Color_RGB_050324.png","width":5001,"height":2986,"caption":"MCE"},"image":{"@id":"https:\/\/mcecleanenergy.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mceCleanEnergy\/","https:\/\/x.com\/MCECleanEnergy","https:\/\/www.instagram.com\/mcecleanenergy\/","https:\/\/www.linkedin.com\/company\/mcecleanenergy\/","https:\/\/www.youtube.com\/c\/Mcecleanenergy\/","https:\/\/en.wikipedia.org\/wiki\/Community_Choice_Aggregation#Marin_Clean_Energy"]},{"@type":"Person","@id":"https:\/\/mcecleanenergy.org\/#\/schema\/person\/8ce2f62799413aaa2b6868dc9b471748","name":"\u0a30\u0a4b\u0a39\u0a28","image":{"@type":"ImageObject","inLanguage":"pa-IN","@id":"https:\/\/secure.gravatar.com\/avatar\/08c0249ed3a34e3695a3cb94fc48aa840d636d2ba6af19ac1dd65e5303c3c992?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/08c0249ed3a34e3695a3cb94fc48aa840d636d2ba6af19ac1dd65e5303c3c992?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/08c0249ed3a34e3695a3cb94fc48aa840d636d2ba6af19ac1dd65e5303c3c992?s=96&d=mm&r=g","caption":"Rohan"},"url":"https:\/\/mcecleanenergy.org\/pa\/author\/rohan\/"}]}},"_links":{"self":[{"href":"https:\/\/mcecleanenergy.org\/pa\/wp-json\/wp\/v2\/posts\/40318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mcecleanenergy.org\/pa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mcecleanenergy.org\/pa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mcecleanenergy.org\/pa\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mcecleanenergy.org\/pa\/wp-json\/wp\/v2\/comments?post=40318"}],"version-history":[{"count":0,"href":"https:\/\/mcecleanenergy.org\/pa\/wp-json\/wp\/v2\/posts\/40318\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mcecleanenergy.org\/pa\/wp-json\/wp\/v2\/media\/40319"}],"wp:attachment":[{"href":"https:\/\/mcecleanenergy.org\/pa\/wp-json\/wp\/v2\/media?parent=40318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mcecleanenergy.org\/pa\/wp-json\/wp\/v2\/categories?post=40318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mcecleanenergy.org\/pa\/wp-json\/wp\/v2\/tags?post=40318"}],"curies":[{"name":"\u0a21\u0a2c\u0a32\u0a2f\u0a42\u0a2a\u0a40","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}