{"id":17951,"date":"2024-03-12T20:38:33","date_gmt":"2024-03-13T03:38:33","guid":{"rendered":"https:\/\/mcecleanenergy.org\/venue\/831-latour-court-suite-a\/"},"modified":"2024-03-12T20:38:33","modified_gmt":"2024-03-13T03:38:33","slug":"831-latour-court-suite-a","status":"publish","type":"tribe_venue","link":"https:\/\/mcecleanenergy.org\/ru\/%D0%BC%D0%B5%D1%81%D1%82%D0%BE-%D0%BF%D1%80%D0%BE%D0%B2%D0%B5%D0%B4%D0%B5%D0%BD%D0%B8%D1%8F\/831-latour-court-suite-a\/","title":{"rendered":"831 Latour Court, Suite A"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":0,"template":"","meta":{"_acf_changed":false,"_searchwp_excluded":"","footnotes":""},"class_list":["post-17951","tribe_venue","type-tribe_venue","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>831 Latour Court, Suite A - MCE \u2013 Community Choice Energy<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"831 Latour Court, Suite A\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mcecleanenergy.org\/ru\/venue\/831-latour-court-suite-a\/\" \/>\n<meta property=\"og:site_name\" content=\"MCE \u2013 Community Choice Energy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mceCleanEnergy\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MCECleanEnergy\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/venue\\\/831-latour-court-suite-a\\\/\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/venue\\\/831-latour-court-suite-a\\\/\",\"name\":\"831 Latour Court, Suite A - MCE \u2013 Community Choice Energy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#website\"},\"datePublished\":\"2024-03-13T03:38:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/venue\\\/831-latour-court-suite-a\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mcecleanenergy.org\\\/venue\\\/831-latour-court-suite-a\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/venue\\\/831-latour-court-suite-a\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mcecleanenergy.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"831 Latour Court, Suite A\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#website\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/\",\"name\":\"MCE \u2013 Community Choice Energy\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mcecleanenergy.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#organization\",\"name\":\"MCE\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/MCE_Logo_Full-Color_RGB_050324.png\",\"contentUrl\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/MCE_Logo_Full-Color_RGB_050324.png\",\"width\":5001,\"height\":2986,\"caption\":\"MCE\"},\"image\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mceCleanEnergy\\\/\",\"https:\\\/\\\/x.com\\\/MCECleanEnergy\",\"https:\\\/\\\/www.instagram.com\\\/mcecleanenergy\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mcecleanenergy\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/Mcecleanenergy\\\/\",\"https:\\\/\\\/en.wikipedia.org\\\/wiki\\\/Community_Choice_Aggregation#Marin_Clean_Energy\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u041b\u0430\u0442our-\u043a\u043e\u0440\u0442, 831, \u0441\u044c\u044e\u0438\u0442 \u0410 \u2014 MCE (Community Choice Energy)","robots":{"index":"noindex","follow":"follow"},"og_locale":"ru_RU","og_type":"article","og_title":"831 Latour Court, Suite A","og_url":"https:\/\/mcecleanenergy.org\/ru\/venue\/831-latour-court-suite-a\/","og_site_name":"MCE \u2013 Community Choice Energy","article_publisher":"https:\/\/www.facebook.com\/mceCleanEnergy\/","twitter_card":"summary_large_image","twitter_site":"@MCECleanEnergy","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mcecleanenergy.org\/venue\/831-latour-court-suite-a\/","url":"https:\/\/mcecleanenergy.org\/venue\/831-latour-court-suite-a\/","name":"\u041b\u0430\u0442our-\u043a\u043e\u0440\u0442, 831, \u0441\u044c\u044e\u0438\u0442 \u0410 \u2014 MCE (Community Choice Energy)","isPartOf":{"@id":"https:\/\/mcecleanenergy.org\/#website"},"datePublished":"2024-03-13T03:38:33+00:00","breadcrumb":{"@id":"https:\/\/mcecleanenergy.org\/venue\/831-latour-court-suite-a\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mcecleanenergy.org\/venue\/831-latour-court-suite-a\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mcecleanenergy.org\/venue\/831-latour-court-suite-a\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mcecleanenergy.org\/"},{"@type":"ListItem","position":2,"name":"831 Latour Court, Suite A"}]},{"@type":"WebSite","@id":"https:\/\/mcecleanenergy.org\/#website","url":"https:\/\/mcecleanenergy.org\/","name":"MCE - Community Choice Energy","description":"","publisher":{"@id":"https:\/\/mcecleanenergy.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mcecleanenergy.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/mcecleanenergy.org\/#organization","name":"MCE","url":"https:\/\/mcecleanenergy.org\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/mcecleanenergy.org\/#\/schema\/logo\/image\/","url":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/MCE_Logo_Full-Color_RGB_050324.png","contentUrl":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/MCE_Logo_Full-Color_RGB_050324.png","width":5001,"height":2986,"caption":"MCE"},"image":{"@id":"https:\/\/mcecleanenergy.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mceCleanEnergy\/","https:\/\/x.com\/MCECleanEnergy","https:\/\/www.instagram.com\/mcecleanenergy\/","https:\/\/www.linkedin.com\/company\/mcecleanenergy\/","https:\/\/www.youtube.com\/c\/Mcecleanenergy\/","https:\/\/en.wikipedia.org\/wiki\/Community_Choice_Aggregation#Marin_Clean_Energy"]}]}},"_links":{"self":[{"href":"https:\/\/mcecleanenergy.org\/ru\/wp-json\/wp\/v2\/tribe_venue\/17951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mcecleanenergy.org\/ru\/wp-json\/wp\/v2\/tribe_venue"}],"about":[{"href":"https:\/\/mcecleanenergy.org\/ru\/wp-json\/wp\/v2\/types\/tribe_venue"}],"author":[{"embeddable":true,"href":"https:\/\/mcecleanenergy.org\/ru\/wp-json\/wp\/v2\/users\/6"}],"version-history":[{"count":0,"href":"https:\/\/mcecleanenergy.org\/ru\/wp-json\/wp\/v2\/tribe_venue\/17951\/revisions"}],"wp:attachment":[{"href":"https:\/\/mcecleanenergy.org\/ru\/wp-json\/wp\/v2\/media?parent=17951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}