{"id":14563,"date":"2024-03-07T08:58:11","date_gmt":"2024-03-07T16:58:11","guid":{"rendered":"https:\/\/mcecleanenergy.org\/?post_type=board-members&#038;p=14563"},"modified":"2025-04-18T11:05:06","modified_gmt":"2025-04-18T18:05:06","slug":"holi-thier","status":"publish","type":"board-members","link":"https:\/\/mcecleanenergy.org\/tl\/board-members\/holi-thier\/","title":{"rendered":"Holli Thier"},"content":{"rendered":"","protected":false},"featured_media":8110,"template":"","meta":{"_acf_changed":true,"_searchwp_excluded":""},"location":[565],"class_list":["post-14563","board-members","type-board-members","status-publish","has-post-thumbnail","hentry","location-marin-county"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Holli Thier - MCE \u2013 Community Choice Energy<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Holli Thier\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mcecleanenergy.org\/tl\/board-members\/holi-thier\/\" \/>\n<meta property=\"og:site_name\" content=\"MCE \u2013 Community Choice Energy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mceCleanEnergy\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-18T18:05:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2023\/10\/holli-thier-website.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"337\" \/>\n\t<meta property=\"og:image:height\" content=\"226\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MCECleanEnergy\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/board-members\\\/holi-thier\\\/\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/board-members\\\/holi-thier\\\/\",\"name\":\"Holli Thier - MCE \u2013 Community Choice Energy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/board-members\\\/holi-thier\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/board-members\\\/holi-thier\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/holli-thier-website.jpg\",\"datePublished\":\"2024-03-07T16:58:11+00:00\",\"dateModified\":\"2025-04-18T18:05:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/board-members\\\/holi-thier\\\/#breadcrumb\"},\"inLanguage\":\"tl\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mcecleanenergy.org\\\/board-members\\\/holi-thier\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"tl\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/board-members\\\/holi-thier\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/holli-thier-website.jpg\",\"contentUrl\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/holli-thier-website.jpg\",\"width\":337,\"height\":226},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/board-members\\\/holi-thier\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mcecleanenergy.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Holli Thier\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#website\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/\",\"name\":\"MCE \u2013 Community Choice Energy\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mcecleanenergy.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"tl\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#organization\",\"name\":\"MCE\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"tl\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/MCE_Logo_Full-Color_RGB_050324.png\",\"contentUrl\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/MCE_Logo_Full-Color_RGB_050324.png\",\"width\":5001,\"height\":2986,\"caption\":\"MCE\"},\"image\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mceCleanEnergy\\\/\",\"https:\\\/\\\/x.com\\\/MCECleanEnergy\",\"https:\\\/\\\/www.instagram.com\\\/mcecleanenergy\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mcecleanenergy\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/Mcecleanenergy\\\/\",\"https:\\\/\\\/en.wikipedia.org\\\/wiki\\\/Community_Choice_Aggregation#Marin_Clean_Energy\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Holli Thier - MCE \u2013 Community Choice Energy","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Holli Thier","og_url":"https:\/\/mcecleanenergy.org\/tl\/board-members\/holi-thier\/","og_site_name":"MCE \u2013 Community Choice Energy","article_publisher":"https:\/\/www.facebook.com\/mceCleanEnergy\/","article_modified_time":"2025-04-18T18:05:06+00:00","og_image":[{"width":337,"height":226,"url":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2023\/10\/holli-thier-website.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@MCECleanEnergy","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mcecleanenergy.org\/board-members\/holi-thier\/","url":"https:\/\/mcecleanenergy.org\/board-members\/holi-thier\/","name":"Holli Thier - MCE \u2013 Community Choice Energy","isPartOf":{"@id":"https:\/\/mcecleanenergy.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mcecleanenergy.org\/board-members\/holi-thier\/#primaryimage"},"image":{"@id":"https:\/\/mcecleanenergy.org\/board-members\/holi-thier\/#primaryimage"},"thumbnailUrl":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2023\/10\/holli-thier-website.jpg","datePublished":"2024-03-07T16:58:11+00:00","dateModified":"2025-04-18T18:05:06+00:00","breadcrumb":{"@id":"https:\/\/mcecleanenergy.org\/board-members\/holi-thier\/#breadcrumb"},"inLanguage":"tl","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mcecleanenergy.org\/board-members\/holi-thier\/"]}]},{"@type":"ImageObject","inLanguage":"tl","@id":"https:\/\/mcecleanenergy.org\/board-members\/holi-thier\/#primaryimage","url":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2023\/10\/holli-thier-website.jpg","contentUrl":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2023\/10\/holli-thier-website.jpg","width":337,"height":226},{"@type":"BreadcrumbList","@id":"https:\/\/mcecleanenergy.org\/board-members\/holi-thier\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mcecleanenergy.org\/"},{"@type":"ListItem","position":2,"name":"Holli Thier"}]},{"@type":"WebSite","@id":"https:\/\/mcecleanenergy.org\/#website","url":"https:\/\/mcecleanenergy.org\/","name":"MCE \u2013 Community Choice Energy","description":"","publisher":{"@id":"https:\/\/mcecleanenergy.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mcecleanenergy.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"tl"},{"@type":"Organization","@id":"https:\/\/mcecleanenergy.org\/#organization","name":"MCE","url":"https:\/\/mcecleanenergy.org\/","logo":{"@type":"ImageObject","inLanguage":"tl","@id":"https:\/\/mcecleanenergy.org\/#\/schema\/logo\/image\/","url":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/MCE_Logo_Full-Color_RGB_050324.png","contentUrl":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/MCE_Logo_Full-Color_RGB_050324.png","width":5001,"height":2986,"caption":"MCE"},"image":{"@id":"https:\/\/mcecleanenergy.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mceCleanEnergy\/","https:\/\/x.com\/MCECleanEnergy","https:\/\/www.instagram.com\/mcecleanenergy\/","https:\/\/www.linkedin.com\/company\/mcecleanenergy\/","https:\/\/www.youtube.com\/c\/Mcecleanenergy\/","https:\/\/en.wikipedia.org\/wiki\/Community_Choice_Aggregation#Marin_Clean_Energy"]}]}},"_links":{"self":[{"href":"https:\/\/mcecleanenergy.org\/tl\/wp-json\/wp\/v2\/board-members\/14563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mcecleanenergy.org\/tl\/wp-json\/wp\/v2\/board-members"}],"about":[{"href":"https:\/\/mcecleanenergy.org\/tl\/wp-json\/wp\/v2\/types\/board-members"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mcecleanenergy.org\/tl\/wp-json\/wp\/v2\/media\/8110"}],"wp:attachment":[{"href":"https:\/\/mcecleanenergy.org\/tl\/wp-json\/wp\/v2\/media?parent=14563"}],"wp:term":[{"taxonomy":"location","embeddable":true,"href":"https:\/\/mcecleanenergy.org\/tl\/wp-json\/wp\/v2\/location?post=14563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}