{"id":23202,"date":"2024-03-21T19:59:19","date_gmt":"2024-03-22T02:59:19","guid":{"rendered":"https:\/\/mcecleanenergy.org\/service-areas\/larkspur\/"},"modified":"2025-02-28T11:48:45","modified_gmt":"2025-02-28T19:48:45","slug":"larkspur","status":"publish","type":"service-areas","link":"https:\/\/mcecleanenergy.org\/zh\/service-areas\/larkspur\/","title":{"rendered":"\u62c9\u514b\u65af\u73c0"},"content":{"rendered":"","protected":false},"author":2,"featured_media":0,"template":"","location":[],"class_list":["post-23202","service-areas","type-service-areas","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Larkspur - MCE \u2013 Community Choice Energy<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Larkspur\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mcecleanenergy.org\/zh\/service-areas\/larkspur\/\" \/>\n<meta property=\"og:site_name\" content=\"MCE \u2013 Community Choice Energy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mceCleanEnergy\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-28T19:48:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MCECleanEnergy\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/service-areas\\\/larkspur\\\/\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/service-areas\\\/larkspur\\\/\",\"name\":\"Larkspur - MCE \u2013 Community Choice Energy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#website\"},\"datePublished\":\"2024-03-22T02:59:19+00:00\",\"dateModified\":\"2025-02-28T19:48:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/service-areas\\\/larkspur\\\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mcecleanenergy.org\\\/service-areas\\\/larkspur\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/service-areas\\\/larkspur\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mcecleanenergy.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Service Areas\",\"item\":\"https:\\\/\\\/mcecleanenergy.org\\\/service-areas\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Larkspur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#website\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/\",\"name\":\"MCE \u2013 Community Choice Energy\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mcecleanenergy.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#organization\",\"name\":\"MCE\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/MCE_Logo_Full-Color_RGB_050324.png\",\"contentUrl\":\"https:\\\/\\\/mcecleanenergy.org\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/MCE_Logo_Full-Color_RGB_050324.png\",\"width\":5001,\"height\":2986,\"caption\":\"MCE\"},\"image\":{\"@id\":\"https:\\\/\\\/mcecleanenergy.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mceCleanEnergy\\\/\",\"https:\\\/\\\/x.com\\\/MCECleanEnergy\",\"https:\\\/\\\/www.instagram.com\\\/mcecleanenergy\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mcecleanenergy\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/Mcecleanenergy\\\/\",\"https:\\\/\\\/en.wikipedia.org\\\/wiki\\\/Community_Choice_Aggregation#Marin_Clean_Energy\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Larkspur - MCE \u2013 Community Choice Energy","robots":{"index":"noindex","follow":"follow"},"og_locale":"zh_CN","og_type":"article","og_title":"Larkspur","og_url":"https:\/\/mcecleanenergy.org\/zh\/service-areas\/larkspur\/","og_site_name":"MCE \u2013 Community Choice Energy","article_publisher":"https:\/\/www.facebook.com\/mceCleanEnergy\/","article_modified_time":"2025-02-28T19:48:45+00:00","twitter_card":"summary_large_image","twitter_site":"@MCECleanEnergy","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mcecleanenergy.org\/service-areas\/larkspur\/","url":"https:\/\/mcecleanenergy.org\/service-areas\/larkspur\/","name":"Larkspur - MCE \u2013 Community Choice Energy","isPartOf":{"@id":"https:\/\/mcecleanenergy.org\/#website"},"datePublished":"2024-03-22T02:59:19+00:00","dateModified":"2025-02-28T19:48:45+00:00","breadcrumb":{"@id":"https:\/\/mcecleanenergy.org\/service-areas\/larkspur\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mcecleanenergy.org\/service-areas\/larkspur\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mcecleanenergy.org\/service-areas\/larkspur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mcecleanenergy.org\/"},{"@type":"ListItem","position":2,"name":"Service Areas","item":"https:\/\/mcecleanenergy.org\/service-areas\/"},{"@type":"ListItem","position":3,"name":"Larkspur"}]},{"@type":"WebSite","@id":"https:\/\/mcecleanenergy.org\/#website","url":"https:\/\/mcecleanenergy.org\/","name":"MCE - \u793e\u533a\u9009\u62e9\u80fd\u6e90","description":"","publisher":{"@id":"https:\/\/mcecleanenergy.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mcecleanenergy.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"},{"@type":"Organization","@id":"https:\/\/mcecleanenergy.org\/#organization","name":"MCE","url":"https:\/\/mcecleanenergy.org\/","logo":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/mcecleanenergy.org\/#\/schema\/logo\/image\/","url":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/MCE_Logo_Full-Color_RGB_050324.png","contentUrl":"https:\/\/mcecleanenergy.org\/wp-content\/uploads\/2024\/05\/MCE_Logo_Full-Color_RGB_050324.png","width":5001,"height":2986,"caption":"MCE"},"image":{"@id":"https:\/\/mcecleanenergy.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mceCleanEnergy\/","https:\/\/x.com\/MCECleanEnergy","https:\/\/www.instagram.com\/mcecleanenergy\/","https:\/\/www.linkedin.com\/company\/mcecleanenergy\/","https:\/\/www.youtube.com\/c\/Mcecleanenergy\/","https:\/\/en.wikipedia.org\/wiki\/Community_Choice_Aggregation#Marin_Clean_Energy"]}]}},"_links":{"self":[{"href":"https:\/\/mcecleanenergy.org\/zh\/wp-json\/wp\/v2\/service-areas\/23202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mcecleanenergy.org\/zh\/wp-json\/wp\/v2\/service-areas"}],"about":[{"href":"https:\/\/mcecleanenergy.org\/zh\/wp-json\/wp\/v2\/types\/service-areas"}],"author":[{"embeddable":true,"href":"https:\/\/mcecleanenergy.org\/zh\/wp-json\/wp\/v2\/users\/2"}],"wp:attachment":[{"href":"https:\/\/mcecleanenergy.org\/zh\/wp-json\/wp\/v2\/media?parent=23202"}],"wp:term":[{"taxonomy":"location","embeddable":true,"href":"https:\/\/mcecleanenergy.org\/zh\/wp-json\/wp\/v2\/location?post=23202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}